{"id":74222,"date":"2025-11-01T08:00:55","date_gmt":"2025-11-01T11:00:55","guid":{"rendered":"https:\/\/www.adf.org.br\/home\/?p=74222"},"modified":"2025-10-24T09:39:10","modified_gmt":"2025-10-24T12:39:10","slug":"dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/","title":{"rendered":"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja"},"content":{"rendered":"<figure style=\"width: 585px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/adf.org.br\/velario\/todosossantos?origem=28609\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" title=\"Nossa Senhora \u00e9 Rainha dos Santos, Anjos e dos Homens\" src=\"https:\/\/img.cancaonova.com\/cnimages\/canais\/uploads\/sites\/6\/2014\/08\/formacao_nossa-senhora-rainha-dos-anjos-dos-santos-e-dos-homens-artigo.jpg\" alt=\"Nossa Senhora \u00e9 Rainha dos Santos, Anjos e dos Homens\" width=\"585\" height=\"439\" \/><\/a><figcaption class=\"wp-caption-text\">Nossa Senhora \u00e9 Rainha dos Santos, Anjos e dos Homens<\/figcaption><\/figure>\n<p>Na data de hoje, a Santa Igreja celebra a festa em honra de Todos os Santos.<\/p>\n<p><span style=\"color: #000000;\">Esta solenidade \u00e9 tamb\u00e9m um convite para admirarmos o exemplo de vida que eles nos deixaram.<\/span><\/p>\n<p><span style=\"color: #000000;\">\u00c9 uma homenagem a todos os Santos desconhecidos, que carregaram em sil\u00eancio a sua cruz de cada dia.<\/span><\/p>\n<p style=\"padding-left: 40px;\"><span style=\"color: #800080;\"><strong>Os Santos s\u00e3o amados todos do mesmo modo por Deus, que leva em conta a fidelidade e o amor que recebeu de cada um deles<\/strong>.<\/span><\/p>\n<p><span style=\"color: #000000;\">A grande multid\u00e3o de Santos que est\u00e1 na gl\u00f3ria de Deus \u00e9 para todos n\u00f3s motivo de imensa alegria, pois podemos contar com sua intercess\u00e3o por n\u00f3s e pela nossa salva\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"color: #000000;\">Neste dia \u00e9 celebrada a Igreja Triunfante, constitu\u00edda por todos os bem-aventurados que salvaram sua alma e est\u00e3o no Para\u00edso, na posse da vis\u00e3o beat\u00edfica de Deus.<\/span><\/p>\n<p><span style=\"color: #000000;\">Os inumer\u00e1veis her\u00f3is an\u00f4nimos, na sua imensa maioria esquecidos pelos demais homens e pela Hist\u00f3ria.<\/span><\/p>\n<p><span style=\"color: #000000;\">Que ao longo dos tempos foram passando desta vida para a Eternidade em estado de gra\u00e7a, e pelos m\u00e9ritos da Paix\u00e3o de Nosso Senhor Jesus Cristo foram sendo admitidos no Para\u00edso.<\/span><\/p>\n<p><span style=\"color: #000000;\">Embora esquecidos na Terra, s\u00e3o santos e s\u00e3o honrados pela Igreja na data de hoje.<\/span><\/p>\n<h2><span style=\"color: #800080;\">Nossa Senhora \u00e9 a Rainha de todos os Santos<\/span><\/h2>\n<p><strong><span style=\"color: #000000;\">Dentre tantos santos de Deus, \u00e9 imposs\u00edvel falar de santidade, sem lembrar do modelo primordial, do molde de santidade que \u00e9 Nossa Senhora, a Rainha de todos os Santos.<\/span><\/strong><\/p>\n<p><span style=\"color: #000000;\">S\u00e3o Bernardino de Sena afirmava que:<\/span><\/p>\n<blockquote><p><strong style=\"color: #000000;\">\u201cDesde o momento em que Maria aceitou ser M\u00e3e do Verbo Eterno, mereceu tornar-se Rainha do mundo e de todas as criaturas\u201d<\/strong><\/p><\/blockquote>\n<p><span style=\"color: #000000;\">Quantas s\u00e3o as criaturas que servem a Deus, tantas tamb\u00e9m devem servir a Maria. Por conseguinte est\u00e3o sujeitas ao dom\u00ednio de Maria, os homens, os anjos e todas as criaturas do c\u00e9u e da terra, porque tudo est\u00e1 sujeito ao Imp\u00e9rio de Deus.<\/span><\/p>\n<p><span style=\"color: #000000;\">Maria \u00e9 Rainha das coisas vis\u00edveis e invis\u00edveis, reina na eternidade, reina sobr<\/span>e todos os santos, p<span style=\"color: #000000;\">ois foi essa mesma donzela de Nazar\u00e9 que em Bel\u00e9m dava a conhecer o Filho de Deus aos homens e que hoje e sempre nos continua a levar, como M\u00e3e, at\u00e9 Ele.<\/span><\/p>\n<h2><span style=\"color: #800080;\">Nossa Senhora, modelo de Santidade.<\/span><\/h2>\n<p>Maria n\u00e3o \u00e9 apenas o meio por onde o imp\u00e9rio de Deus passa, mas \u00e9 a Rainha que decide por uma vontade pr\u00f3pria, produzida em rela\u00e7\u00e3o \u00e0 vontade de seu Filho, o Grande Rei.<\/p>\n<p>Nossa Senhora \u00e9 uma obra-prima, \u00e9 o modelo perfeito para ser seguido. Os que querem dedicar-se a Deus, alcan\u00e7ando em suas vidas a santidade, devem imitar Nossa Senhora.<\/p>\n<p>Santo Agostinho gostava de invocar Nossa Senhora com o titulo de Forma Dei, a Forma de Deus, ou seja, Ela \u00e9 a forma no qual Deus usa para realizar uma grande produ\u00e7\u00e3o de Santos.<\/p>\n<p>Foi no seio da Virgem Santa que o Verbo de Deus foi gerado e, \u00e9 em Maria que n\u00f3s crist\u00e3os somos moldados para um dia na P\u00e1tria Celeste cantarmos louvores a Deus junto com anjos e Santos.<\/p>\n<p>O pecado jamais venceu Maria, jamais lhe tocou, \u00e9 molde perfeito, imagem e semelhan\u00e7a de Deus, \u00e9 o molde divino onde quem nele \u00e9 modelado fica em seguida modelado em Jesus Cristo.<br \/>\nDevemos chegar \u00e0 santidade por Maria. Ela \u00e9 esse molde no qual Deus vai modelando seus santos, de maneira suave, feliz, sem grandes riscos de cansa\u00e7o e des\u00e2nimo.<\/p>\n<p>Buscar a santidade \u00e9 algo heroico, mas sozinhos teremos um caminho muito mais \u00e1rduo e dif\u00edcil, com prova\u00e7\u00f5es de des\u00e2nimo e queda.<\/p>\n<blockquote><p>Com Maria, ainda sim teremos essas prova\u00e7\u00f5es, mas possuiremos uma m\u00e3o que fortemente segurar\u00e1 nossa m\u00e3o puxando-nos novamente para o caminho rumo a Jesus.<\/p><\/blockquote>\n<p>S\u00f3 Deus d\u00e1 a gra\u00e7a necess\u00e1ria para a santidade. Mas se a gra\u00e7a \u00e9 de Deus, contudo \u00e9 dada por Maria, que \u00e9 nossa Advogada e Medianeira. Deus d\u00e1 as gra\u00e7as, Maria as obt\u00e9m e as distribui.<\/p>\n<p>Santidade \u00e9 confiar em Deus, \u00e9 aceitar as cruzes que nos s\u00e3o oferecidas, \u00e9 sofrer por amor, \u00e9 renunciar a si mesmo para ser mais com Ele, \u00e9 morrer a cada dia para viver para Ele.<\/p>\n<p>Deus que exaltou Maria no C\u00e9u, quis que sua glorifica\u00e7\u00e3o tamb\u00e9m fosse realizada na terra. Pondo em suas m\u00e3os o cetro da miseric\u00f3rdia e da caridade, todos os favores, gra\u00e7as e todas as miseric\u00f3rdias de Deus chegaram \u00e0 terra pelas m\u00e3os de Nossa Senhora.<\/p>\n<p>Atrav\u00e9s da nossa M\u00e3e Sant\u00edssima todos os santos e santas de Deus alcan\u00e7aram a gl\u00f3ria do C\u00e9u.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Na data de hoje, a Santa Igreja celebra a festa em honra de Todos os Santos. Esta solenidade \u00e9 tamb\u00e9m um convite para admirarmos o exemplo de vida que eles nos deixaram. \u00c9 uma homenagem a todos os Santos desconhecidos, que carregaram em sil\u00eancio a sua cruz de cada dia. Os Santos s\u00e3o amados todos [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":74229,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[967,4675,5307,5308],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja<\/title>\n<meta name=\"description\" content=\"A igreja celebra hoje o Dia de Todos os Santos, mas \u00e9 imposs\u00edvel falar dessa data sem falarmos de Maria, Rainha dos Santos\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja\" \/>\n<meta property=\"og:description\" content=\"A igreja celebra hoje o Dia de Todos os Santos, mas \u00e9 imposs\u00edvel falar dessa data sem falarmos de Maria, Rainha dos Santos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-01T11:00:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-10-24T12:39:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2023\/11\/FEsta-todos-os-santos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"576\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2023\/11\/FEsta-todos-os-santos.jpg\",\"contentUrl\":\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2023\/11\/FEsta-todos-os-santos.jpg\",\"width\":1024,\"height\":576,\"caption\":\"Festa todos os santos\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/\",\"name\":\"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#primaryimage\"},\"datePublished\":\"2025-11-01T11:00:55+00:00\",\"dateModified\":\"2025-10-24T12:39:10+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\"},\"description\":\"A igreja celebra hoje o Dia de Todos os Santos, mas \\u00e9 imposs\\u00edvel falar dessa data sem falarmos de Maria, Rainha dos Santos\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\",\"name\":\"Gabriel Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"caption\":\"Gabriel Barbosa\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja","description":"A igreja celebra hoje o Dia de Todos os Santos, mas \u00e9 imposs\u00edvel falar dessa data sem falarmos de Maria, Rainha dos Santos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/","og_locale":"pt_BR","og_type":"article","og_title":"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja","og_description":"A igreja celebra hoje o Dia de Todos os Santos, mas \u00e9 imposs\u00edvel falar dessa data sem falarmos de Maria, Rainha dos Santos","og_url":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2025-11-01T11:00:55+00:00","article_modified_time":"2025-10-24T12:39:10+00:00","og_image":[{"width":1024,"height":576,"url":"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2023\/11\/FEsta-todos-os-santos.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Barbosa","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#primaryimage","inLanguage":"pt-BR","url":"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2023\/11\/FEsta-todos-os-santos.jpg","contentUrl":"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2023\/11\/FEsta-todos-os-santos.jpg","width":1024,"height":576,"caption":"Festa todos os santos"},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#webpage","url":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/","name":"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#primaryimage"},"datePublished":"2025-11-01T11:00:55+00:00","dateModified":"2025-10-24T12:39:10+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753"},"description":"A igreja celebra hoje o Dia de Todos os Santos, mas \u00e9 imposs\u00edvel falar dessa data sem falarmos de Maria, Rainha dos Santos","breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/dia-de-todos-os-santos-maria-rainha-de-todos-os-santos-da-igreja\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"Dia de todos os Santos: Maria, Rainha de todos os Santos da Igreja"}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753","name":"Gabriel Barbosa","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","caption":"Gabriel Barbosa"},"url":"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/74222"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=74222"}],"version-history":[{"count":5,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/74222\/revisions"}],"predecessor-version":[{"id":79861,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/74222\/revisions\/79861"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media\/74229"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=74222"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=74222"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=74222"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}