{"id":54793,"date":"2019-09-19T07:30:02","date_gmt":"2019-09-19T10:30:02","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=54793"},"modified":"2019-09-19T07:30:02","modified_gmt":"2019-09-19T10:30:02","slug":"mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/","title":{"rendered":"Mensagem de F\u00e1tima: As prova\u00e7\u00f5es dos Tr\u00eas Pastorinhos"},"content":{"rendered":"<div class=\"video-youtube\" style=\"text-align: center;\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/wEfQPgTYcDY\" width=\"560\" height=\"315\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><br \/>\n<\/iframe><\/div>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<h6 style=\"text-align: center;\"><span style=\"font-weight: 400; color: #000000; font-family: verdana, geneva, sans-serif; font-size: 14pt;\">Compartilhe o v\u00eddeo!\u00a0<\/span><\/h6>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span style=\"color: #800080;\">Assim voc\u00ea ajudar\u00e1 na divulga\u00e7\u00e3o da Mensagem de Nossa Senhora para o Brasil e para o mundo.<\/span>\u00a0<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<blockquote>\n<p style=\"text-align: center;\"><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><a href=\"https:\/\/www.youtube.com\/user\/devotosdefatima?sub_confirmation=1\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #0000ff;\"><b>Inscreva-se aqui <\/b><\/span><\/a><strong>no nosso canal no Youtube e acompanhe a hist\u00f3ria completa das apari\u00e7\u00f5es da Sant\u00edssima Virgem em F\u00e1tima.\u00a0<\/strong><\/span><\/p>\n<\/blockquote>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><i>Todas as pessoas que fizeram a inscri\u00e7\u00e3o no canal ser\u00e3o lembradas nas ora\u00e7\u00f5es di\u00e1rias realizadas pelos volunt\u00e1rios e religiosos que apoiam a associa\u00e7\u00e3o.<\/i><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span style=\"color: #800080;\"><b>Dica: <\/b><\/span><span style=\"font-weight: 400;\"><strong>Acione o sininho para receber a notifica\u00e7\u00e3o dos novos v\u00eddeos.<\/strong> \ud83d\ude09<\/span><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<hr \/>\n<p><a href=\"https:\/\/adf.org.br\/apostolosdefatima?origem=11737#Participar\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"aligncenter wp-image-54504 size-full\" src=\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2019\/09\/Ap\u00f3stolo-de-F\u00e1tima-Logo-2.png\" alt=\"Ap\u00f3stolo de F\u00e1tima - Logo 2\" width=\"209\" height=\"185\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400; color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">Voc\u00ea gostaria de enviar <strong>seu nome ao Santu\u00e1rio de F\u00e1tima<\/strong>, em Portugal?<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/adf.org.br\/apostolosdefatima?origem=11737#ChanceUnica\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone wp-image-54289 size-medium\" src=\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2019\/08\/Santu\u00e1rio-de-F\u00e1tima-Portugal-300x205.jpg\" alt=\"Santu\u00e1rio de F\u00e1tima, Portugal\" width=\"300\" height=\"205\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400; color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">E receber o <strong>lindo ter\u00e7o abaixo da Virgem Sant\u00edssima com os Tr\u00eas Pastorinhos<\/strong>, j\u00e1 bento por um sacerdote?<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"tel:08006082128\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone wp-image-54455 size-medium\" src=\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2019\/09\/Ter\u00e7o-de-Nossa-Senhora-de-F\u00e1tima-5-300x239.png\" alt=\"Ter\u00e7o de Nossa Senhora de F\u00e1tima 5\" width=\"300\" height=\"239\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-weight: 400; color: #000000; font-family: verdana, geneva, sans-serif; font-size: 14pt;\">Ent\u00e3o ligue para:\u00a0<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"tel:08006082128\" target=\"_blank\" rel=\"noopener noreferrer\"><strong><span style=\"color: #0000ff; font-family: verdana, geneva, sans-serif; font-size: 24pt;\">0800 608 2128<\/span><\/strong><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><i><span style=\"font-weight: 400;\">Dica: Se estiver no celular, somente tecle no n\u00famero para discar automaticamente.<\/span><\/i><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #003366; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">E saiba como <span style=\"color: #000000;\">ajudar a levar a devo\u00e7\u00e3o do Imaculado Cora\u00e7\u00e3o de Maria<\/span> para milhares de pessoas, principalmente para aquelas que mais precisam abrigar-se no amor de Nossa Senhora.<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><em><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">Lembrando que a <strong>liga\u00e7\u00e3o \u00e9 gratuita<\/strong> para qualquer regi\u00e3o do Brasil e estamos dispon\u00edveis de segunda a sexta-feira, das 08h \u00e0s 18h.\u00a0<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<blockquote>\n<p style=\"text-align: center;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; color: #003366;\">*** PRESENTES DE AGRADECIMENTO ***<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><span style=\"font-weight: 400;\">Para agradecermos o seu apoio neste apostolado, <strong><span style=\"color: #003366;\">voc\u00ea poder\u00e1 receber incr\u00edveis presentes<\/span><\/strong> como um maravilhoso ter\u00e7o, uma estampa de Maria Sant\u00edssima com o Menino Jesus e muito mais! <span style=\"color: #003366;\">(<\/span><\/span><span style=\"color: #003366;\"><i>Converse com uma de nossas colaboradoras para saber todos os detalhes da campanha<\/i>)<\/span><\/span><\/p>\n<\/blockquote>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"https:\/\/adf.org.br\/apostolosdefatima?origem=11737\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"alignnone wp-image-54794 size-medium\" src=\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2019\/09\/Nossa-Senhora-e-os-Tr\u00eas-Pastorinhos-1-176x300.png\" alt=\"Nossa Senhora e os Tr\u00eas Pastorinhos\" width=\"176\" height=\"300\" \/><\/a><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #003366; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><i><span style=\"font-weight: 400;\">\u201cJesus quer estabelecer no mundo a devo\u00e7\u00e3o ao Meu Imaculado Cora\u00e7\u00e3o.<\/span><\/i><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #003366; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><i><span style=\"font-weight: 400;\">A quem a abra\u00e7ar, prometo a <\/span><\/i><b><i>salva\u00e7\u00e3o<\/i><\/b><i><span style=\"font-weight: 400;\">. E ser\u00e3o queridas de DEUS estas almas, como flores postas por Mim a adornar o Seu trono.\u201d<\/span><\/i><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #000000;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\">Nossa Senhora nas apari\u00e7\u00f5es aos Tr\u00eas Pastorinhos<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><strong><span style=\"color: #0000ff; font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><a style=\"color: #0000ff;\" href=\"https:\/\/adf.org.br\/apostolosdefatima\/2\/form\/?origem=11737\" target=\"_blank\" rel=\"noopener noreferrer\">Clique aqui para ajudar Nossa Senhora, sem sair de casa.<\/a>\u00a0<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>. Compartilhe o v\u00eddeo!\u00a0 . Assim voc\u00ea ajudar\u00e1 na divulga\u00e7\u00e3o da Mensagem de Nossa Senhora para o Brasil e para o mundo.\u00a0 . Inscreva-se aqui no nosso canal no Youtube e acompanhe a hist\u00f3ria completa das apari\u00e7\u00f5es da Sant\u00edssima Virgem em F\u00e1tima.\u00a0 . Todas as pessoas que fizeram a inscri\u00e7\u00e3o no canal ser\u00e3o lembradas nas [&hellip;]<\/p>\n","protected":false},"author":31,"featured_media":54796,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,2323,56,101],"tags":[43,2242,3241,57,58],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mensagem de F\u00e1tima: As prova\u00e7\u00f5es dos Tr\u00eas Pastorinhos - Associa\u00e7\u00e3o Devotos de F\u00e1tima<\/title>\n<meta name=\"description\" content=\"Veja quais foram as prova\u00e7\u00f5es que os tr\u00eas pastorinhos tiveram que passar antes da terceira apari\u00e7\u00e3o de Nossa Senhora, em F\u00e1tima...Ap\u00f3stolos..\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mensagem de F\u00e1tima: As prova\u00e7\u00f5es dos Tr\u00eas Pastorinhos - Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"og:description\" content=\"Veja quais foram as prova\u00e7\u00f5es que os tr\u00eas pastorinhos tiveram que passar antes da terceira apari\u00e7\u00e3o de Nossa Senhora, em F\u00e1tima...Ap\u00f3stolos..\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2019-09-19T10:30:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/\",\"name\":\"Mensagem de F\\u00e1tima: As prova\\u00e7\\u00f5es dos Tr\\u00eas Pastorinhos - Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#primaryimage\"},\"datePublished\":\"2019-09-19T10:30:02+00:00\",\"dateModified\":\"2019-09-19T10:30:02+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\"},\"description\":\"Veja quais foram as prova\\u00e7\\u00f5es que os tr\\u00eas pastorinhos tiveram que passar antes da terceira apari\\u00e7\\u00e3o de Nossa Senhora, em F\\u00e1tima...Ap\\u00f3stolos..\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mensagem de F\\u00e1tima: As prova\\u00e7\\u00f5es dos Tr\\u00eas Pastorinhos\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\",\"name\":\"Gabriel Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"caption\":\"Gabriel Barbosa\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mensagem de F\u00e1tima: As prova\u00e7\u00f5es dos Tr\u00eas Pastorinhos - Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Veja quais foram as prova\u00e7\u00f5es que os tr\u00eas pastorinhos tiveram que passar antes da terceira apari\u00e7\u00e3o de Nossa Senhora, em F\u00e1tima...Ap\u00f3stolos..","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/","og_locale":"pt_BR","og_type":"article","og_title":"Mensagem de F\u00e1tima: As prova\u00e7\u00f5es dos Tr\u00eas Pastorinhos - Associa\u00e7\u00e3o Devotos de F\u00e1tima","og_description":"Veja quais foram as prova\u00e7\u00f5es que os tr\u00eas pastorinhos tiveram que passar antes da terceira apari\u00e7\u00e3o de Nossa Senhora, em F\u00e1tima...Ap\u00f3stolos..","og_url":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2019-09-19T10:30:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Barbosa","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#primaryimage","inLanguage":"pt-BR","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#webpage","url":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/","name":"Mensagem de F\u00e1tima: As prova\u00e7\u00f5es dos Tr\u00eas Pastorinhos - Associa\u00e7\u00e3o Devotos de F\u00e1tima","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#primaryimage"},"datePublished":"2019-09-19T10:30:02+00:00","dateModified":"2019-09-19T10:30:02+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753"},"description":"Veja quais foram as prova\u00e7\u00f5es que os tr\u00eas pastorinhos tiveram que passar antes da terceira apari\u00e7\u00e3o de Nossa Senhora, em F\u00e1tima...Ap\u00f3stolos..","breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/mensagem-de-fatima-as-provacoes-dos-tres-pastorinhos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"Mensagem de F\u00e1tima: As prova\u00e7\u00f5es dos Tr\u00eas Pastorinhos"}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753","name":"Gabriel Barbosa","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","caption":"Gabriel Barbosa"},"url":"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/54793"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=54793"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/54793\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media\/54796"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=54793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=54793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=54793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}