{"id":44248,"date":"2018-06-05T00:00:21","date_gmt":"2018-06-05T03:00:21","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=44248"},"modified":"2018-06-05T00:00:21","modified_gmt":"2018-06-05T03:00:21","slug":"lancada-coracao-nosso-senhor","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/","title":{"rendered":"Estudos apontam como foi a lan\u00e7ada que feriu o Cora\u00e7\u00e3o de Nosso Senhor."},"content":{"rendered":"<figure id=\"attachment_44249\" aria-describedby=\"caption-attachment-44249\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-44249\" title=\"Ilustra\u00e7\u00e3o &quot;O homem do Sud\u00e1rio&quot;\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2017\/06\/O-homem-do-Sud\u00e1rio-Lanzada-100712-\u00a9Luis-Guillermo-Arroyave-Curitiba.jpg\" alt=\"O homem do Sud\u00e1rio Lanzada, 100712 \u00a9Luis Guillermo Arroyave, Curitiba\" width=\"560\" height=\"541\" \/><figcaption id=\"caption-attachment-44249\" class=\"wp-caption-text\">Ilustra\u00e7\u00e3o &#8220;O homem do Sud\u00e1rio&#8221;<\/figcaption><\/figure>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"color: #800080;\"><strong>Estudos patrocinados pela Universidade Cat\u00f3lica de M\u00farcia (UCAM), na Espanha, conclu\u00edram que o Santo Sud\u00e1rio de Turim e o Sud\u00e1rio de Oviedo envolveram a mesma pessoa.<\/strong><\/span><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\n<span style=\"font-size: 14pt;\"><strong>I<\/strong><\/span>sso confirmou conclus\u00f5es de outras an\u00e1lises.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">O realmente importante na novidade identificada \u00e9 que os dois tecidos apresentam sinais de que, depois de morto;<\/span><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800000;\"><br \/>\nO corpo para o qual eles serviram de c\u00e2mara mortu\u00e1ria \u201csofreu um ferimento\u201d no lado direito que o atravessou inteiramente, saindo pelas costas.<br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/span><\/strong><\/p>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #003300;\">O tremendo ferimento concorda com o Evangelho de S\u00e3o Jo\u00e3o quando relata que um centuri\u00e3o romano perfurou o lado de Cristo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #003300;\">31. Os judeus temeram que os corpos ficassem na cruz durante o s\u00e1bado, (&#8230;) Rogaram a Pilatos que se lhes quebrassem as pernas e fossem retirados. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #003300;\">32. Vieram os soldados e quebraram as pernas do primeiro e do outro, que com ele foram crucificados. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #003300;\">33. Chegando, por\u00e9m, a Jesus, como o vissem j\u00e1 morto, n\u00e3o lhe quebraram as pernas, <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #003300;\">34. mas um dos soldados abriu-lhe o lado com uma lan\u00e7a e, imediatamente, saiu sangue e \u00e1gua. (&#8230;)<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #003300;\">36. Assim se cumpriu a Escritura: Nenhum dos seus ossos ser\u00e1 quebrado (Ex 12,46). <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #003300;\">37. E diz em outra parte a Escritura: Olhar\u00e3o para aquele que transpassaram (Zc 12,10)\u201d. (<a style=\"color: #003300;\" href=\"http:\/\/www.bibliacatolica.com.br\/biblia-ave-maria\/sao-joao\/19\/\" target=\"_blank\" rel=\"noopener noreferrer\"><i><b>S\u00e3o Jo\u00e3o, 19 \u2013 31-37<\/b><\/i><\/a>)<\/span><\/p><\/blockquote>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">A conclus\u00e3o foi dada a conhecer pela Universidade Cat\u00f3lica de M\u00farcia (Espanha).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> O estudo m\u00e9dico-forense foi dirigido por Alfonso S\u00e1nchez Hermosilla, pesquisador desse centro de estudos, informou ACIDigital.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">O Dr. S\u00e1nchez Hermosilla \u00e9 m\u00e9dico forense do Instituto de Medicina Legal de M\u00farcia;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Diretor da Equipe de Pesquisa do Centro Espanhol de Sindonologia (EDICES) e assessor cient\u00edfico do Centro Internacional de Sindonologia de Turim.<\/span><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"color: #000080;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\">Nas conclus\u00f5es, l\u00ea-se que o estudo conjunto do Santo Sud\u00e1rio de Turim e do Sud\u00e1rio de Oviedo:\u00a0<\/span><\/strong><\/span><\/p>\n<blockquote><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">1. \u201cn\u00e3o s\u00f3 confirma que ambos envolveram a mesma pessoa, <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">2. \u201ccomo tamb\u00e9m, que depois de morto e em posi\u00e7\u00e3o vertical, sofreu um ferimento profundo <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">3. \u201cque atravessou o t\u00f3rax direito, com a entrada pela quinta costela e sa\u00edda pela quarta, perto da coluna vertebral e da esc\u00e1pula direita, <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">4. \u201cdeixando marcas de co\u00e1gulos de sangue e l\u00edquido peric\u00e1rdico em ambos os panos <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">(no Santo Sud\u00e1rio pelo seu contato com os orif\u00edcios da entrada e da sa\u00edda, e no Sud\u00e1rio de Oviedo com o da sa\u00edda)\u201d.<\/span><\/p><\/blockquote>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Tudo isso, indicou a UCAM:<\/span><\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\"> \u201cEst\u00e1 de acordo com o que foi relatado no Evangelho de Jo\u00e3o, cap\u00edtulo 19, vers\u00edculos 33-34: <\/span><\/strong><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">\u2018Mas, vindo a Jesus, e vendo-o j\u00e1 morto, n\u00e3o lhe quebraram as pernas. <\/span><\/strong><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">Contudo um dos soldados lhe furou o lado com uma lan\u00e7a, e logo saiu sangue e \u00e1gua\u2019\u201d.<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Para chegar a essa conclus\u00e3o, explica a Universidade, foram realizados:<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> \u201cEstudos antropom\u00e9tricos, criminal\u00edsticos, anat\u00f4micos e anatomopatol\u00f3gicos do Santo Sud\u00e1rio de Turim e do Sud\u00e1rio de Oviedo\u201d. <\/span><br \/>\n<span style=\"color: #ffffff;\">.<\/span><\/p>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">\u201cSeus resultados sup\u00f5em novas descobertas da Equipe de Pesquisa da UCAM;<\/span><\/p><\/blockquote>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">Que est\u00e1 estudando o Sud\u00e1rio de Oviedo e que anteriormente encontrou outras evid\u00eancias de que ambos os tecidos envolveram a mesma pessoa\u201d;<\/span><\/p><\/blockquote>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">Indicou em seu site.<\/span><\/p><\/blockquote>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">O trabalho informa tamb\u00e9m que foram realizados:<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> \u201cEstudos do sangue, da presen\u00e7a de polens, da conserva\u00e7\u00e3o do material do tecido (linho) e da determina\u00e7\u00e3o de contaminantes org\u00e2nicos e inorg\u00e2nicos\u201d.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">\u201cAs manchas de sangue que foram estudadas sempre estiveram l\u00e1, mas ningu\u00e9m as havia estudado, e s\u00e3o as \u00fanicas com essas caracter\u00edsticas. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">\u201cAt\u00e9 o momento, foram atribu\u00eddas a marcas causadas pelas feridas da flagela\u00e7\u00e3o\u201d, assinalou S\u00e1nchez Hermosilla.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">A Universidade explicou que:<\/span><\/p><\/blockquote>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\"> \u201cAs manchas (&#8230;) nas quais se centra o estudo compartilham caracter\u00edsticas comuns e s\u00e3o muito diferentes do resto;<\/span><\/p><\/blockquote>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">Pela sua morfologia e complexidade depois da an\u00e1lise macrosc\u00f3pica, como uma alta concentra\u00e7\u00e3o hem\u00e1tica no centro e uma aureola mais clara e perfilada\u201d.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">\u201cAl\u00e9m disso, essas manchas se tornam invis\u00edveis quando observadas com um filtro infravermelho;<\/span><\/p><\/blockquote>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\"><strong>Como normalmente acontece nas manchas causadas pelo sangue de cad\u00e1ver, ao contr\u00e1rio do que ocorre com o sangue de uma pessoa que est\u00e1 viva (&#8230;).<\/strong> <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">\u201cNo Sud\u00e1rio existe apenas outra mancha com caracter\u00edsticas semelhantes, chamada \u2018Mancha em acorde\u00e3o\u2019, atribu\u00edda \u00e0 mesma origem com m\u00e1cula e;<\/span><\/p><\/blockquote>\n<blockquote class=\"tr_bq\"><p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\">Consequentemente, do tecido ter sido dobrado v\u00e1rias vezes em v\u00e1rias \u2018partes\u2019, ficando sobre o inverso da grande mancha central\u201d acrescentou.<\/span><\/p><\/blockquote>\n<p><span style=\"color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">O estudo descreve com detalhe \u201cos tecidos e \u00f3rg\u00e3os que atravessaram o objeto pontiagudo em sua hipot\u00e9tica trajet\u00f3ria\u201d.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">E apoia \u201ca hip\u00f3tese de que <b>quem administrou o \u2018golpe de gra\u00e7a\u2019 tinha experi\u00eanci<\/b>a;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Pois ao colocar a folha da arma na posi\u00e7\u00e3o horizontal poderia evitar facilmente as costelas;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\"><b>Sem ter que tentar v\u00e1rias vezes, algo que aparentemente n\u00e3o aconteceu, pois n\u00e3o aparece o que denominamos na Medicina Forense \u2018marcas das les\u00f5es\u2019\u201d.<\/b><\/span><\/p>\n<h5 style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\"><b>Mais uma prova proveniente da bot\u00e2nica<\/b><\/span><\/h5>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Antes desta nova descoberta, no transcurso da investiga\u00e7\u00e3o;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> \u201cF<b>oi descoberto no Sud\u00e1rio de Oviedo um gr\u00e3o de p\u00f3len <\/b>de uma planta que;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Segundo a pale\u00f3loga da EDICES, Marzia Boi, \u00e9 compat\u00edvel com a esp\u00e9cie bot\u00e2nica <i><b>Helichrysum Sp<\/b><\/i>., tamb\u00e9m identificada no Sud\u00e1rio de Turim\u201d.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Os cientistas \u201cdescartaram tratar-se de uma contamina\u00e7\u00e3o posterior, pois est\u00e1 aderido ao sangue. <\/span><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\"><br \/>\nOu seja, chegou \u00e0 rel\u00edquia no mesmo tempo que o sangue, e n\u00e3o foi de forma aleat\u00f3ria\u201d.<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">A equipe liderada pelo Dr. S\u00e1nchez Hermosilla incluiu:<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> Jes\u00fas Garc\u00eda Iglesias, professor de Minas da Universidade de Oviedo;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> Marzia Boi, pale\u00f3loga e bi\u00f3loga; <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Juan Manuel Mi\u00f1arro, professor no Departamento de Escultura da Universidade de Sevilha;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> Antonio G\u00f3mez G\u00f3mez e Felipe Montero Ortego.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<em><span style=\"font-family: verdana, geneva, sans-serif; font-size: 10pt; color: #000000;\">Fonte:\u00a0cienciaconfirmaigreja.blogspot.com.br<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">* \u00a0* \u00a0*<\/span><\/strong><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\n<a href=\"https:\/\/adf.org.br\/minhaoferta\/?origem=6667\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"aligncenter wp-image-46853 size-full\" title=\"bot\u00e3o sacolinha adf\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2017\/06\/bt_oferta_ADF-1-1-4.png\" alt=\"bt_oferta_ADF-1 (1)\" width=\"600\" height=\"190\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Estudos patrocinados pela Universidade Cat\u00f3lica de M\u00farcia (UCAM), na Espanha, conclu\u00edram que o Santo Sud\u00e1rio de Turim e o Sud\u00e1rio de Oviedo envolveram a mesma pessoa.<\/p>\n","protected":false},"author":31,"featured_media":46855,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[1845,1447,943,1449,1522],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Estudos apontam como foi a lan\u00e7ada que feriu Nosso Senhor.<\/title>\n<meta name=\"description\" content=\"Estudos apontam como foi a lan\u00e7ada que feriu o Cora\u00e7\u00e3o de Nosso Senhor. Atrav\u00e9s de pesquisas, estudiosos forenses apontam resultados, veja!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Estudos apontam como foi a lan\u00e7ada que feriu Nosso Senhor.\" \/>\n<meta property=\"og:description\" content=\"Estudos apontam como foi a lan\u00e7ada que feriu o Cora\u00e7\u00e3o de Nosso Senhor. Atrav\u00e9s de pesquisas, estudiosos forenses apontam resultados, veja!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-05T03:00:21+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/\",\"name\":\"Estudos apontam como foi a lan\\u00e7ada que feriu Nosso Senhor.\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#primaryimage\"},\"datePublished\":\"2018-06-05T03:00:21+00:00\",\"dateModified\":\"2018-06-05T03:00:21+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\"},\"description\":\"Estudos apontam como foi a lan\\u00e7ada que feriu o Cora\\u00e7\\u00e3o de Nosso Senhor. Atrav\\u00e9s de pesquisas, estudiosos forenses apontam resultados, veja!\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Estudos apontam como foi a lan\\u00e7ada que feriu o Cora\\u00e7\\u00e3o de Nosso Senhor.\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\",\"name\":\"Gabriel Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"caption\":\"Gabriel Barbosa\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Estudos apontam como foi a lan\u00e7ada que feriu Nosso Senhor.","description":"Estudos apontam como foi a lan\u00e7ada que feriu o Cora\u00e7\u00e3o de Nosso Senhor. Atrav\u00e9s de pesquisas, estudiosos forenses apontam resultados, veja!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/","og_locale":"pt_BR","og_type":"article","og_title":"Estudos apontam como foi a lan\u00e7ada que feriu Nosso Senhor.","og_description":"Estudos apontam como foi a lan\u00e7ada que feriu o Cora\u00e7\u00e3o de Nosso Senhor. Atrav\u00e9s de pesquisas, estudiosos forenses apontam resultados, veja!","og_url":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2018-06-05T03:00:21+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Barbosa","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#primaryimage","inLanguage":"pt-BR","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#webpage","url":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/","name":"Estudos apontam como foi a lan\u00e7ada que feriu Nosso Senhor.","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#primaryimage"},"datePublished":"2018-06-05T03:00:21+00:00","dateModified":"2018-06-05T03:00:21+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753"},"description":"Estudos apontam como foi a lan\u00e7ada que feriu o Cora\u00e7\u00e3o de Nosso Senhor. Atrav\u00e9s de pesquisas, estudiosos forenses apontam resultados, veja!","breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/lancada-coracao-nosso-senhor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"Estudos apontam como foi a lan\u00e7ada que feriu o Cora\u00e7\u00e3o de Nosso Senhor."}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753","name":"Gabriel Barbosa","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","caption":"Gabriel Barbosa"},"url":"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/44248"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=44248"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/44248\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media\/46855"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=44248"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=44248"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=44248"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}