{"id":44124,"date":"2017-05-30T02:00:12","date_gmt":"2017-05-30T05:00:12","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=44124"},"modified":"2017-05-30T02:00:12","modified_gmt":"2017-05-30T05:00:12","slug":"nome-do-seu-anjo","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/","title":{"rendered":"Qual \u00e9 o nome do seu Anjo? Gabriel? Serafim? Miguel? Uriel?"},"content":{"rendered":"<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<div class=\"video-container\"><iframe loading=\"lazy\" src=\"\/\/www.youtube.com\/embed\/Xg86DuuI4WM?rel=0&amp;modestbranding=1&amp;showinfo=0&amp;controls=0\" width=\"640\" height=\"360\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/div>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><a class=\"link-origem\" href=\"https:\/\/aliancadosanjos.com.br\/participe\/?origem=4547\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"aligncenter wp-image-44126 size-full\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2017\/05\/Bot_Vermelho2.png\" alt=\"Bot_Vermelho2\" width=\"388\" height=\"111\" \/><\/a><\/p>\n<p><span style=\"color: #ffffff;\">.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\">Seu nome na <\/span><span style=\"color: #ff0000;\"><b>Missa dos Anjos<\/b><\/span><span style=\"font-weight: 400;\">, celebrada mensalmente. (<span style=\"color: #0000ff;\"><strong><a class=\"link-origem\" style=\"color: #0000ff;\" href=\"https:\/\/aliancadosanjos.com.br\/participe\/?origem=4547\" target=\"_blank\" rel=\"noopener noreferrer\">eu quero!<\/a><\/strong><\/span>)<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"color: #ff0000;\"><b>Um diploma de membro<\/b><\/span><span style=\"font-weight: 400;\"> desse grupo, para voc\u00ea emoldurar e colocar em um lugar de destaque em sua casa, ou trabalho. (<span style=\"color: #0000ff;\"><strong><a class=\"link-origem\" style=\"color: #0000ff;\" href=\"https:\/\/aliancadosanjos.com.br\/participe\/?origem=4547\" target=\"_blank\" rel=\"noopener noreferrer\">eu quero!<\/a><\/strong><\/span>)<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\">&#8220;Vig\u00edlia Di\u00e1ria de Ora\u00e7\u00f5es&#8221;\u00a0Diariamente, nos 7 dias da semana, das 18:00 horas \u00e0s 6:00 da manh\u00e3, nossos volunt\u00e1rios se revezam recitando continuamente o Santo Ros\u00e1rio por voc\u00ea.<\/span><\/span><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\"> Ou seja, especialmente para voc\u00ea ser\u00e3o <span style=\"color: #ff0000;\"><strong>rezados de\u00a018.000 a 20.000 ter\u00e7os por ano<\/strong><\/span>. (<span style=\"color: #0000ff;\"><strong><a class=\"link-origem\" style=\"color: #0000ff;\" href=\"https:\/\/aliancadosanjos.com.br\/participe\/?origem=4547\" target=\"_blank\" rel=\"noopener noreferrer\">eu quero!<\/a><\/strong><\/span>)<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li style=\"font-weight: 400;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-weight: 400;\">Acesso exclusivo a uma <\/span><span style=\"color: #ff0000;\"><b>p\u00e1gina particular na internet<\/b><\/span><span style=\"font-weight: 400;\"> para voc\u00ea incluir todos os seus pedidos de gra\u00e7as. (<span style=\"color: #0000ff;\"><strong><a class=\"link-origem\" style=\"color: #0000ff;\" href=\"https:\/\/aliancadosanjos.com.br\/participe\/?origem=4547\" target=\"_blank\" rel=\"noopener noreferrer\">eu quero!<\/a><\/strong><\/span>)<\/span><\/span><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">* \u00a0* \u00a0*<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Qual o nome do seu Anjo da Guarda?<\/p>\n","protected":false},"author":31,"featured_media":44127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[750,752],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra.<\/title>\n<meta name=\"description\" content=\"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra, saiba mais sobre seu Anjo da Guarda, fiel guardi\u00e3o da sua alma.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra.\" \/>\n<meta property=\"og:description\" content=\"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra, saiba mais sobre seu Anjo da Guarda, fiel guardi\u00e3o da sua alma.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2017-05-30T05:00:12+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/\",\"name\":\"Qual ser\\u00e1 o nome do seu Anjo, assista o v\\u00eddeo abaixo e descubra.\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#primaryimage\"},\"datePublished\":\"2017-05-30T05:00:12+00:00\",\"dateModified\":\"2017-05-30T05:00:12+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\"},\"description\":\"Qual ser\\u00e1 o nome do seu Anjo, assista o v\\u00eddeo abaixo e descubra, saiba mais sobre seu Anjo da Guarda, fiel guardi\\u00e3o da sua alma.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Qual \\u00e9 o nome do seu Anjo? Gabriel? Serafim? Miguel? Uriel?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\",\"name\":\"Gabriel Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"caption\":\"Gabriel Barbosa\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra.","description":"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra, saiba mais sobre seu Anjo da Guarda, fiel guardi\u00e3o da sua alma.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/","og_locale":"pt_BR","og_type":"article","og_title":"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra.","og_description":"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra, saiba mais sobre seu Anjo da Guarda, fiel guardi\u00e3o da sua alma.","og_url":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2017-05-30T05:00:12+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Barbosa","Est. tempo de leitura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#primaryimage","inLanguage":"pt-BR","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#webpage","url":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/","name":"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra.","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#primaryimage"},"datePublished":"2017-05-30T05:00:12+00:00","dateModified":"2017-05-30T05:00:12+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753"},"description":"Qual ser\u00e1 o nome do seu Anjo, assista o v\u00eddeo abaixo e descubra, saiba mais sobre seu Anjo da Guarda, fiel guardi\u00e3o da sua alma.","breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/nome-do-seu-anjo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"Qual \u00e9 o nome do seu Anjo? Gabriel? Serafim? Miguel? Uriel?"}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753","name":"Gabriel Barbosa","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","caption":"Gabriel Barbosa"},"url":"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/44124"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=44124"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/44124\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media\/44127"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=44124"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=44124"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=44124"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}