{"id":43470,"date":"2017-04-10T00:00:48","date_gmt":"2017-04-10T03:00:48","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=43470"},"modified":"2017-04-10T00:00:48","modified_gmt":"2017-04-10T03:00:48","slug":"descoberta-roma","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/","title":{"rendered":"Descoberta nas catacumbas de Roma."},"content":{"rendered":"<figure id=\"attachment_43473\" aria-describedby=\"caption-attachment-43473\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-43473\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2017\/03\/imagem-catacumba.jpg\" alt=\"imagem-catacumba\" width=\"560\" height=\"360\" \/><figcaption id=\"caption-attachment-43473\" class=\"wp-caption-text\">No centro, Jesus como o Bom Pastor, nos \u00e2ngulos os Ap\u00f3stolos Pedro, Paulo, Jo\u00e3o e Andr\u00e9.<\/figcaption><\/figure>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"color: #ffffff;\">.<\/span><br \/>\n<strong><span style=\"color: #800080;\">Em 2010 foram descobertos os retratos mais antigos dos Ap\u00f3stolos S\u00e3o Pedro, S\u00e3o Paulo, S\u00e3o Jo\u00e3o e Santo Andr\u00e9.<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-size: 14pt;\"><strong>E<\/strong><\/span>les estavam numa catacumba recuperada sob um moderno pr\u00e9dio de uma empresa de seguros em Roma.<br \/>\n<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">As imagens datam da segunda metade do s\u00e9culo IV e decoram o teto do t\u00famulo de uma aristocr\u00e1tica dama crist\u00e3 ligado \u00e0 catacumba de Santa Tecla.<br \/>\n<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Eles vinham sendo trabalhados pelos restauradores;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Com t\u00e9cnicas laser para queimar acumula\u00e7\u00f5es sedimentares seculares de sais e desvendar os originais em todo seu esplendor. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Os rostos dos Ap\u00f3stolos aparecem em medalh\u00f5es nos quatro cantos da sala principal.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Eles fazem parte de um conjunto pict\u00f3rico mais vasto;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Que rodeia uma imagem de Nosso Senhor Jesus Cristo apresentado como o Bom Pastor, que foi sendo revelado em fases sucessivas. <\/span><\/p>\n<p style=\"padding-left: 90px;\">\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">\u201cEstas s\u00e3o as primeiras imagens dos Ap\u00f3stolos\u201d;<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nAnunciou Fabrizio Bisconti, superintendente das catacumbas, por indica\u00e7\u00e3o da Comiss\u00e3o Pontif\u00edcia para a Arqueologia Sagrada.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">As cores predominantes s\u00e3o o ocre, o preto, o verde e o amarelo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">As catacumbas cont\u00eam algumas das primeir\u00edssimas provas do culto e devo\u00e7\u00e3o aos Ap\u00f3stolos no nascente cristianismo, explicaram representantes do Vaticano.<\/span><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\"><br \/>\nBarbara Mazzei, respons\u00e1vel pelo trabalho de restaura\u00e7\u00e3o;<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nDisse que todas as descri\u00e7\u00f5es anteriores de S\u00e3o Pedro e S\u00e3o Paulo se encontravam em narra\u00e7\u00f5es escritas.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Mas agora temos seus rostos fixados nos quatro cantos da pintura do teto da sala subterr\u00e2nea, num posicionamento devocional por natureza.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Por isso s\u00e3o os mais antigos \u00edcones religiosos conhecidos at\u00e9 o presente, noticiou oportunamente o\u00a0jornal &#8220;The Dallas Morning News&#8221;.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Barbara Mazzei\u00a0explicou que;<\/span><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000080;\"><br \/>\nEm aten\u00e7\u00e3o ao ano de S\u00e3o Paulo, comemorado em 2009, foi anunciada primeiramente a descoberta da pintura do Ap\u00f3stolo das Gentes. <\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nPor\u00e9m, os especialistas sabiam que uma crosta de carbonato de c\u00e1lcio cobria mais imagens;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">E que poderiam ser apresentadas a p\u00fablico somente ap\u00f3s completar sofisticadas tarefas de limpeza.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Por fim, o momento do extraordin\u00e1rio an\u00fancio chegou.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Apresentando as imagens aos jornalistas, monsenhor Giovanni Carru disse que as catacumbas:<\/span><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\"><br \/>\n\u201cS\u00e3o um testemunho eloquente do Cristianismo em suas origens\u201d.<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">A sala sepulcral da nobre romana cat\u00f3lica passou a ser denominada \u201cCub\u00edculo dos Ap\u00f3stolos\u201d devido aos afrescos ali descobertos.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">J\u00e1 os especialistas a chamam de \u201cO Col\u00e9gio dos Ap\u00f3stolos\u201d, representado em torno do Bom Pastor.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Fabrizio Bisconti explicou que nas pinturas das catacumbas pode se contemplar:<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> \u201cA g\u00eanese, as sementes da iconografia crist\u00e3\u201d;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Desde o simples peixe usado para simbolizar a Cristo at\u00e9 o pr\u00f3prio Cristo ressuscitando a L\u00e1zaro.<\/span><\/p>\n<p style=\"padding-left: 90px;\">\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">\u201cEsse foi o tempo em que o culto dos Ap\u00f3stolos estava nascendo e se desenvolvendo\u201d;<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nE a arte das catacumbas n\u00e3o pintava somente os m\u00e1rtires ou cenas b\u00edblicas. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Na mesma sala h\u00e1 afrescos representando o profeta Daniel na cova dos le\u00f5es;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Os tr\u00eas Reis Magos entregando presentes ao Menino Jesus, o sacrif\u00edcio de Isaac por Abra\u00e3o.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Numa outra parede est\u00e1 representada a nobre dama que teria mandado fazer as pinturas;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Ornada com joias, v\u00e9u e um \u201cestilo de penteado de cabelo\u201d, s\u00edmbolo de categoria social elevada na antiga Roma, acrescentou Bisconti.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Mazzei contou que quando os restauradores ingressaram na c\u00e2mera mortu\u00e1ria em 2008;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Todas as paredes apareciam inteiramente brancas, cobertas pela crosta de carbonato de c\u00e1lcio com 4 a 5 cm de espessura. <\/span><\/p>\n<p style=\"padding-left: 90px;\">\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"color: #000080;\">O Vaticano, entretanto, possu\u00eda documentos atestando que no local havia pinturas nas paredes e isso impulsionou a procura.<\/span> <\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">No passado os restauradores teriam usado bisturis e escovas de a\u00e7o para remover a crosta branca, mas havia o perigo de danificar as pinturas procuradas.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">O uso do laser resolveu o problema.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Temia-se, por\u00e9m, que a umidade ambiente e a falta de ar pudesse prejudicar o uso da nova tecnologia. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Os pesquisadores tiveram que avan\u00e7ar cautelosamente;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Fazendo da iniciativa um \u201claborat\u00f3rio experimental\u201d do aproveitamento do laser em condi\u00e7\u00f5es extremas adversas.<\/span><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\"><br \/>\nA descoberta veio al\u00e9m do mais confirmar que a devo\u00e7\u00e3o aos Santos representados em imagens \u00e9 pr\u00f3pria do cristianismo original;<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nDevo\u00e7\u00e3o desenvolvida nas catacumbas e depois nas igrejas a c\u00e9u aberto.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Ficou desprovida de fundamento a alega\u00e7\u00e3o feita por iconoclastas orientais, mu\u00e7ulmanos, protestantes e \u201cmodernistas\u201d hodiernos;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Segundo a qual o uso e o culto de imagens n\u00e3o correspondem ao cristianismo aut\u00eantico e original. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Segundo essas vers\u00f5es anticat\u00f3licas e anti-hist\u00f3ricas, o culto das imagens seria uma deturpa\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Tal pervers\u00e3o do culto, dizem eles;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Aconteceu quando os primeiros crist\u00e3os sa\u00edram das catacumbas e passaram a imitar os cultos pag\u00e3os;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Que idolatravam esculturas de pedra, madeira ou pinturas antropom\u00f3rficas.<\/span><\/p>\n<h5 style=\"padding-left: 90px;\">\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\">O culto das imagens corresponde bem \u00e0 Igreja desde seus prim\u00f3rdios;<\/span><\/strong><\/h5>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nSendo merecedor de enc\u00f4mio no esp\u00edrito da doutrina tradicional bimilenar do Catolicismo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">As catacumbas de Santa Tecla n\u00e3o est\u00e3o abertas ao p\u00fablico em geral;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Mas pode se pedir autoriza\u00e7\u00e3o na referida comiss\u00e3o vaticana para visitas em grupo, guiadas por especialistas.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<em><span style=\"font-family: verdana, geneva, sans-serif; font-size: 10pt; color: #000000;\">Fonte: \u00a0cienciaconfirmaigreja.blogspot.com.br<\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">* \u00a0* \u00a0*<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Receba Gra\u00e7as e Ben\u00e7\u00e3o de Nossa Senhora agora mesmo<\/span><\/p>\n<h5 style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Veja como receber sua Medalha Milagrosa pelos correios agora mesmo.<\/span><\/h5>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><strong><span style=\"color: #0000ff;\"><a style=\"color: #0000ff;\" href=\"http:\/\/oratoriodamedalhamilagrosa.org.br\/home\/acenda-sua-vela-30\/?origem=1025\" target=\"_blank\" rel=\"noopener noreferrer\">Clique aqui<\/a><\/span><\/strong> e confira.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-size: 8pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-size: 8pt; color: #ffffff;\">.<\/span><\/p>\n<figure id=\"attachment_35437\" aria-describedby=\"caption-attachment-35437\" style=\"width: 400px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/oratoriodamedalhamilagrosa.org.br\/home\/acenda-sua-vela-30\/?origem=1025\" target=\"_blank\" rel=\"noopener noreferrer\"><img loading=\"lazy\" class=\"wp-image-35437 size-full\" title=\"Clique aqui e receba a Medalha Milagrosa\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/11\/banner_medalha_milagrosa13.gif\" alt=\"Clique aqui para receber sua Medalha Milagrosa pelos correios.\" width=\"400\" height=\"146\" \/><\/a><figcaption id=\"caption-attachment-35437\" class=\"wp-caption-text\">Clique aqui para receber sua Medalha Milagrosa pelos correios.<\/figcaption><\/figure>\n<p><span style=\"color: #0000ff;\"><strong style=\"color: #0000ff;\"><span style=\"color: #ffffff;\">.<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Em 2010 foram descobertos os retratos mais antigos dos Ap\u00f3stolos S\u00e3o Pedro, S\u00e3o Paulo, S\u00e3o Jo\u00e3o e Santo Andr\u00e9.<\/p>\n","protected":false},"author":31,"featured_media":43474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[1102,2209,175,590],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos<\/title>\n<meta name=\"description\" content=\"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos, podem ser os primeiros retratos dos mesmos e a base do culto \u00e0s imagens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos\" \/>\n<meta property=\"og:description\" content=\"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos, podem ser os primeiros retratos dos mesmos e a base do culto \u00e0s imagens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-10T03:00:48+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"\",\"contentUrl\":\"\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/\",\"name\":\"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\\u00f3stolos\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#primaryimage\"},\"datePublished\":\"2017-04-10T03:00:48+00:00\",\"dateModified\":\"2017-04-10T03:00:48+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\"},\"description\":\"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\\u00f3stolos, podem ser os primeiros retratos dos mesmos e a base do culto \\u00e0s imagens.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Descoberta nas catacumbas de Roma.\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\",\"name\":\"Gabriel Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"caption\":\"Gabriel Barbosa\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos","description":"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos, podem ser os primeiros retratos dos mesmos e a base do culto \u00e0s imagens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/","og_locale":"pt_BR","og_type":"article","og_title":"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos","og_description":"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos, podem ser os primeiros retratos dos mesmos e a base do culto \u00e0s imagens.","og_url":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2017-04-10T03:00:48+00:00","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Barbosa","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#primaryimage","inLanguage":"pt-BR","url":"","contentUrl":""},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#webpage","url":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/","name":"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#primaryimage"},"datePublished":"2017-04-10T03:00:48+00:00","dateModified":"2017-04-10T03:00:48+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753"},"description":"Descoberta nas catacumbas de Roma. Imagens do tempo dos ap\u00f3stolos, podem ser os primeiros retratos dos mesmos e a base do culto \u00e0s imagens.","breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/descoberta-roma\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/descoberta-roma\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"Descoberta nas catacumbas de Roma."}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753","name":"Gabriel Barbosa","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","caption":"Gabriel Barbosa"},"url":"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/43470"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=43470"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/43470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media\/43474"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=43470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=43470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=43470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}