{"id":41855,"date":"2016-09-22T00:00:41","date_gmt":"2016-09-22T03:00:41","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=41855"},"modified":"2016-09-22T00:00:41","modified_gmt":"2016-09-22T03:00:41","slug":"horror-da-televisao-brasileira","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/","title":{"rendered":"Cada vez Pior! Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o brasileira. Confira."},"content":{"rendered":"<figure id=\"attachment_41856\" aria-describedby=\"caption-attachment-41856\" style=\"width: 450px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" class=\"wp-image-41856 size-full\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2016\/09\/Televis\u00e3o-infantil-450x300.jpg\" alt=\"Televis\u00e3o, o mal para as crian\u00e7as.\" width=\"450\" height=\"300\" \/><figcaption id=\"caption-attachment-41856\" class=\"wp-caption-text\">Todos devem ficar atentos com os conte\u00fados assistidos nas tvs pelas crian\u00e7as.<\/figcaption><\/figure>\n<p style=\"padding-left: 90px;\"><span style=\"color: #800080;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><br \/>\n<span style=\"color: #ffffff;\">.<\/span><br \/>\nA televis\u00e3o brasileira, que j\u00e1 estava longe de ser recomend\u00e1vel para qualquer pessoa;<\/span><\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><span style=\"font-size: 14pt;\"><strong><br \/>\nS<\/strong><\/span>eja jovem ou adulto \u2013 que deseja sinceramente cumprir com os Mandamentos da lei de Deus, agora recebe carta branca do STF para apresentar conte\u00fados violentos e erotizados a qualquer hor\u00e1rio do dia.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">A nova regulamenta\u00e7\u00e3o entrou em vigor no dia 1 de setembro, e foi comemorada pelas emissoras, que apresentaram o fato como um ben\u00e9fico \u201cfim das restri\u00e7\u00f5es \u00e0 liberdade criativa\u201d e;<\/span><\/p>\n<p><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Uma poss\u00edvel redu\u00e7\u00e3o de custos com seus departamentos respons\u00e1veis pelas censuras.<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"> \u201c[A restri\u00e7\u00e3o de hor\u00e1rios] era um ran\u00e7o de subdesenvolvimento cultural do pa\u00eds\u201d, de acordo com Gustavo Binenbojm, advogado da Abert (Associa\u00e7\u00e3o Brasileira de Emissoras de R\u00e1dio e TV).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">O trecho do Estatuto da Crian\u00e7a e do Adolescente que proibia exibir programas fora dos hor\u00e1rios reservados a cada idade, segundo a classifica\u00e7\u00e3o do Minist\u00e9rio da Justi\u00e7a, foi suprimido pela nova regulamenta\u00e7\u00e3o. <\/span><\/p>\n<p style=\"padding-left: 90px;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #800080;\"><br \/>\nNessa decis\u00e3o, o STF encerrou uma a\u00e7\u00e3o apresentada h\u00e1 15 anos pelo PTB, com apoio da Abert.<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nEm 2015, o novelista Gilberto Braga teve de mudar o enredo de uma personagem, que inicialmente era uma \u201cgarota de programa\u201d, na novela \u201cBabil\u00f4nia\u201d para evitar a classifica\u00e7\u00e3o para 16 anos;<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">O que faria com que a novela das 21h s\u00f3 pudesse ir ao ar \u00e0s 22h. Outras oito produ\u00e7\u00f5es televisivas\u00a0receberam, em 2016, pedidos de esclarecimento do minist\u00e9rio.<\/span><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"color: #800080;\"><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><br \/>\nA classifica\u00e7\u00e3o indicativa ainda existir\u00e1, e deve ser informada no\u00a0in\u00edcio de cada atra\u00e7\u00e3o, para que o jovem saiba que nela ser\u00e3o apresentados conte\u00fados somente para adultos;<\/span><\/strong><\/span><\/p>\n<h5><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><br \/>\nE que portanto ele dever\u00e1 tomar a iniciativa de n\u00e3o assistir televis\u00e3o, se quiser.<\/span><\/h5>\n<p><strong><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Que essa medida vai facilitar a vida dos donos das TVs, ningu\u00e9m duvida. <\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Por\u00e9m, pobres crian\u00e7as, j\u00e1 t\u00e3o bombardeadas na escola, nas ruas e por toda parte com apelos \u00e0 corrup\u00e7\u00e3o moral, agora tamb\u00e9m na televis\u00e3o!<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<em><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\">Fonte:\u00a0<a href=\"http:\/\/ipco.org.br\/ipco\/horario-livre-para-criancas-e-adolescentes-e-banido-da-televisao-brasileira\/#.V-KWDPkrLIU\" target=\"_blank\" rel=\"noopener noreferrer\">http:\/\/ipco.org.br\/<\/a><\/span><\/em><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #ffffff;\">.<\/span><br \/>\n<span style=\"font-family: verdana, geneva, sans-serif; font-size: 12pt; color: #000000;\"><strong>* \u00a0* \u00a0*<\/strong><\/span><\/p>\n<p>.<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">Ligue agora para nossa Central de Ora\u00e7\u00f5es e inclua seus pedidos na<\/span><br \/>\n<span style=\"color: #800080; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><strong>Santa\u00a0Missa de Prote\u00e7\u00e3o da Fam\u00edlia!<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">.<\/span><br \/>\n<span style=\"color: #000000; font-family: verdana, geneva, sans-serif; font-size: 14pt;\"><strong>Ligue agora para:<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">.<\/span><br \/>\n<span style=\"color: #800080; font-family: verdana, geneva, sans-serif; font-size: 24pt;\"><strong>0800 773 11 19<\/strong><\/span><br \/>\n<span style=\"color: #800080; font-family: verdana, geneva, sans-serif; font-size: 12pt;\"><strong>(gr\u00e1tis para todo o Brasil)<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">.<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #ffffff; font-family: verdana, geneva, sans-serif; font-size: 12pt;\">.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A televis\u00e3o brasileira, que j\u00e1 estava longe de ser recomend\u00e1vel para qualquer pessoa;<\/p>\n","protected":false},"author":31,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[1630,1187,688],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o.<\/title>\n<meta name=\"description\" content=\"Cada vez Pior! Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o brasileira. Confira agora mesmo.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o.\" \/>\n<meta property=\"og:description\" content=\"Cada vez Pior! Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o brasileira. Confira agora mesmo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-22T03:00:41+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2016\/09\/Televis\u00e3o-infantil-450x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2016\/09\/Televis\\u00e3o-infantil-450x300.jpg\",\"contentUrl\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2016\/09\/Televis\\u00e3o-infantil-450x300.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/\",\"name\":\"Hor\\u00e1rio livre para crian\\u00e7as e adolescentes \\u00e9 banido da televis\\u00e3o.\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#primaryimage\"},\"datePublished\":\"2016-09-22T03:00:41+00:00\",\"dateModified\":\"2016-09-22T03:00:41+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\"},\"description\":\"Cada vez Pior! Hor\\u00e1rio livre para crian\\u00e7as e adolescentes \\u00e9 banido da televis\\u00e3o brasileira. Confira agora mesmo.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cada vez Pior! Hor\\u00e1rio livre para crian\\u00e7as e adolescentes \\u00e9 banido da televis\\u00e3o brasileira. Confira.\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753\",\"name\":\"Gabriel Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g\",\"caption\":\"Gabriel Barbosa\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o.","description":"Cada vez Pior! Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o brasileira. Confira agora mesmo.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/","og_locale":"pt_BR","og_type":"article","og_title":"Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o.","og_description":"Cada vez Pior! Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o brasileira. Confira agora mesmo.","og_url":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2016-09-22T03:00:41+00:00","og_image":[{"url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2016\/09\/Televis\u00e3o-infantil-450x300.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Barbosa","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2016\/09\/Televis\u00e3o-infantil-450x300.jpg","contentUrl":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2016\/09\/Televis\u00e3o-infantil-450x300.jpg"},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#webpage","url":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/","name":"Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o.","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#primaryimage"},"datePublished":"2016-09-22T03:00:41+00:00","dateModified":"2016-09-22T03:00:41+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753"},"description":"Cada vez Pior! Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o brasileira. Confira agora mesmo.","breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/horror-da-televisao-brasileira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"Cada vez Pior! Hor\u00e1rio livre para crian\u00e7as e adolescentes \u00e9 banido da televis\u00e3o brasileira. Confira."}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/f35a5c5aa7728a3dedf4ea9aa1fc2753","name":"Gabriel Barbosa","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2b2cb2f4637682c5605e8d36818f51ef?s=96&d=mm&r=g","caption":"Gabriel Barbosa"},"url":"https:\/\/www.adf.org.br\/home\/author\/gabrielpmk-com-br\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/41855"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/31"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=41855"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/41855\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=41855"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=41855"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=41855"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}