{"id":3729,"date":"2010-04-14T00:10:44","date_gmt":"2010-04-14T03:10:44","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=3729"},"modified":"2020-06-09T11:51:30","modified_gmt":"2020-06-09T14:51:30","slug":"a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/","title":{"rendered":"A miss\u00e3o da beata Jacinta em salvar a alma dos pecadores \u2013 Parte 3"},"content":{"rendered":"<p><span style=\"text-decoration: underline;\">Uma corda \u00e1spera ao modo de cil\u00edcio<\/span><\/p>\n<p><img loading=\"lazy\" class=\"size-medium wp-image-3731 alignleft\" style=\"margin-right: 20px;\" title=\"Beata_Giacinta_Marto_P\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg\" alt=\"Jacinta n\u00e3o medida esfor\u00e7os pela convers\u00e3o dos pecadores\" width=\"140\" height=\"300\" srcset=\"https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg 140w, https:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1.jpg 220w\" sizes=\"(max-width: 140px) 100vw, 140px\" \/><\/p>\n<p>Na apari\u00e7\u00e3o de agosto \u2014 realizada dias depois do dia 13, pois nesse dia haviam sido raptados pelo administrador de Our\u00e9m, que lhes quis arrancar \u00e0 for\u00e7a o segredo \u2014 a Sant\u00edssima Virgem recomendou-lhes de novo a pr\u00e1tica da mortifica\u00e7\u00e3o: \u201cRezai, rezai muito e fazei sacrif\u00edcios pelos pecadores, que v\u00e3o muitas almas para o inferno, por n\u00e3o haver quem se sacrifique e pe\u00e7a por elas\u201d (II Mem\u00f3ria, p. 75).<\/p>\n<p>Passados alguns dias, caminhando os videntes com suas ovelhas, L\u00facia deparou com um peda\u00e7o de corda de uma carro\u00e7a. Pegando-a, a brincar, atou-a num bra\u00e7o e logo notou que a corda a magoava. Disse ent\u00e3o aos primos: \u201cOlhem, isto faz doer; pod\u00edamos at\u00e1-la \u00e0 cinta e oferecer a Deus este sacrif\u00edcio\u201d\u00a0 (II Mem\u00f3ria, p. 75). Todos aceitaram a id\u00e9ia, e retalhando a corda em tr\u00eas peda\u00e7os, passaram a us\u00e1-la de dia e de noite. A aspereza da corda, apertada demasiadamente, fazia-os sofrer horrivelmente. Jacinta deixava \u00e0s vezes cair algumas l\u00e1grimas, pelo inc\u00f4modo que sentia. L\u00facia dizia-lhe para tirar a corda, mas ela respondia: \u201cN\u00e3o. Quero oferecer este sacrif\u00edcio a Nosso Senhor, em repara\u00e7\u00e3o e pela convers\u00e3o dos pecadores\u201d (II Mem\u00f3ria, p. 75).<\/p>\n<p>Por esta resposta, pode-se ver at\u00e9\u00a0 que ponto Jacinta estava imbu\u00edda do esp\u00edrito de repara\u00e7\u00e3o. Por isso, na apari\u00e7\u00e3o de setembro, Nossa Senhora lhes disse: \u201cDeus est\u00e1 contente com os vossos sacrif\u00edcios, mas n\u00e3o quer que durmais com a corda, trazei-a s\u00f3 durante o dia\u201d (II Mem\u00f3ria, p. 77).<\/p>\n<p>Noutra ocasi\u00e3o, Jacinta deparou com umas urtigas, com as quais se picou. Logo advertiu os companheiros: \u201cOlhem, olhem outra coisa com que nos podemos mortificar!\u201d\u00a0 (cfr. II Mem\u00f3ria, p. 75-76). Desde ent\u00e3o adotaram o costume de dar, de vez em quando, alguns golpes com as urtigas nas pernas, para oferecerem a Deus mais este sacrif\u00edcio.<\/p>\n<p>Estes exemplos edificavam os cat\u00f3licos que liam as Mem\u00f3rias da Irm\u00e3 L\u00facia, onde est\u00e3o narrados. No mundo hedonista de hoje, em que os homens colocam o prazer (l\u00edcito ou il\u00edcito) como bem supremo, que efeito eles causam? A id\u00e9ia de repara\u00e7\u00e3o dos pecados pelo sofrimento, em certos casos levado at\u00e9 o holocausto de si mesmo, lhes escapa completamente. Talvez algum deles diga: \u201cN\u00e3o pensei que o fanatismo religioso chegasse a esse ponto\u201d. Por isso, j\u00e1 S\u00e3o Paulo advertia: \u201cN\u00f3s pregamos a Cristo crucificado, esc\u00e2ndalo para os judeus, loucura para os gentios\u201d (I Cor. 1,23).<\/p>\n<p><em>Fonte: Revista Catolicismo<\/em><\/p>\n<p><br class=\"spacer_\" \/><\/p>\n<p style=\"text-align: right;\"><span style=\"color: #0000ff;\">continua na pr\u00f3xima sexta-feira&#8230;<\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #0000ff;\"> <\/span><\/p>\n<figure id=\"attachment_3735\" aria-describedby=\"caption-attachment-3735\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.adf.org.br\/home\/2010\/03\/participe-da-homenagem-ao-centenario-do-nascimento-da-beata-jacinta-de-fatima\/\"><img loading=\"lazy\" class=\"size-medium wp-image-3735\" title=\"jacinta_topo1\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/jacinta_topo12-300x87.jpg\" alt=\"Clique na imagem e saiba como receber em sua casa o livro que conta a hist\u00f3ria desta crian\u00e7a, que desde a tenra idade j\u00e1 tinha uma f\u00e9 inabal\u00e1vel por Nossa Senhora.\" width=\"300\" height=\"87\" \/><\/a><figcaption id=\"caption-attachment-3735\" class=\"wp-caption-text\">Clique na imagem e saiba como receber em sua casa o livro que conta a hist\u00f3ria desta crian\u00e7a, que desde a tenra idade j\u00e1 tinha uma f\u00e9 inabal\u00e1vel por Nossa Senhora.<\/figcaption><\/figure>\n<p><br class=\"spacer_\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma corda \u00e1spera ao modo de cil\u00edcio Na apari\u00e7\u00e3o de agosto \u2014 realizada dias depois do dia 13, pois nesse dia haviam sido raptados pelo administrador de Our\u00e9m, que lhes quis arrancar \u00e0 for\u00e7a o segredo \u2014 a Sant\u00edssima Virgem recomendou-lhes de novo a pr\u00e1tica da mortifica\u00e7\u00e3o: \u201cRezai, rezai muito e fazei sacrif\u00edcios pelos pecadores, [&hellip;]<\/p>\n","protected":false},"author":27,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20,118],"tags":[43,79,58],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>A miss\u00e3o da beata Jacinta em salvar a alma dos pecadores \u2013 Parte 3 - Associa\u00e7\u00e3o Devotos de F\u00e1tima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"A miss\u00e3o da beata Jacinta em salvar a alma dos pecadores \u2013 Parte 3 - Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"og:description\" content=\"Uma corda \u00e1spera ao modo de cil\u00edcio Na apari\u00e7\u00e3o de agosto \u2014 realizada dias depois do dia 13, pois nesse dia haviam sido raptados pelo administrador de Our\u00e9m, que lhes quis arrancar \u00e0 for\u00e7a o segredo \u2014 a Sant\u00edssima Virgem recomendou-lhes de novo a pr\u00e1tica da mortifica\u00e7\u00e3o: \u201cRezai, rezai muito e fazei sacrif\u00edcios pelos pecadores, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2010-04-14T03:10:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-06-09T14:51:30+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Gabriel Barbosa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg\",\"contentUrl\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/\",\"name\":\"A miss\\u00e3o da beata Jacinta em salvar a alma dos pecadores \\u2013 Parte 3 - Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#primaryimage\"},\"datePublished\":\"2010-04-14T03:10:44+00:00\",\"dateModified\":\"2020-06-09T14:51:30+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/affa494ecf91434f3620f5392de44327\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A miss\\u00e3o da beata Jacinta em salvar a alma dos pecadores \\u2013 Parte 3\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/affa494ecf91434f3620f5392de44327\",\"name\":\"Gabriel Barbosa\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/ecf2eab02e30486a7038f8b2858de06a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/ecf2eab02e30486a7038f8b2858de06a?s=96&d=mm&r=g\",\"caption\":\"Gabriel Barbosa\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/gabriel-aascj\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A miss\u00e3o da beata Jacinta em salvar a alma dos pecadores \u2013 Parte 3 - Associa\u00e7\u00e3o Devotos de F\u00e1tima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/","og_locale":"pt_BR","og_type":"article","og_title":"A miss\u00e3o da beata Jacinta em salvar a alma dos pecadores \u2013 Parte 3 - Associa\u00e7\u00e3o Devotos de F\u00e1tima","og_description":"Uma corda \u00e1spera ao modo de cil\u00edcio Na apari\u00e7\u00e3o de agosto \u2014 realizada dias depois do dia 13, pois nesse dia haviam sido raptados pelo administrador de Our\u00e9m, que lhes quis arrancar \u00e0 for\u00e7a o segredo \u2014 a Sant\u00edssima Virgem recomendou-lhes de novo a pr\u00e1tica da mortifica\u00e7\u00e3o: \u201cRezai, rezai muito e fazei sacrif\u00edcios pelos pecadores, [&hellip;]","og_url":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2010-04-14T03:10:44+00:00","article_modified_time":"2020-06-09T14:51:30+00:00","og_image":[{"url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Gabriel Barbosa","Est. tempo de leitura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg","contentUrl":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2010\/04\/Beata_Giacinta_Marto_P1-140x300.jpg"},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#webpage","url":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/","name":"A miss\u00e3o da beata Jacinta em salvar a alma dos pecadores \u2013 Parte 3 - Associa\u00e7\u00e3o Devotos de F\u00e1tima","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#primaryimage"},"datePublished":"2010-04-14T03:10:44+00:00","dateModified":"2020-06-09T14:51:30+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/affa494ecf91434f3620f5392de44327"},"breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/a-missao-da-beata-jacinta-em-salvar-a-alma-dos-pecadores-parte-3\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"A miss\u00e3o da beata Jacinta em salvar a alma dos pecadores \u2013 Parte 3"}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/affa494ecf91434f3620f5392de44327","name":"Gabriel Barbosa","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/ecf2eab02e30486a7038f8b2858de06a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/ecf2eab02e30486a7038f8b2858de06a?s=96&d=mm&r=g","caption":"Gabriel Barbosa"},"url":"https:\/\/www.adf.org.br\/home\/author\/gabriel-aascj\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/3729"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/27"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=3729"}],"version-history":[{"count":1,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/3729\/revisions"}],"predecessor-version":[{"id":59608,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/3729\/revisions\/59608"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=3729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=3729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=3729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}