{"id":31032,"date":"2015-04-04T13:00:32","date_gmt":"2015-04-04T16:00:32","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=31032"},"modified":"2015-04-04T13:00:32","modified_gmt":"2015-04-04T16:00:32","slug":"depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/","title":{"rendered":"&#8220;Depois das trevas, Luz&#8221; &#8211; Veja os significados da cerimonia de s\u00e1bado"},"content":{"rendered":"<figure id=\"attachment_31034\" aria-describedby=\"caption-attachment-31034\" style=\"width: 450px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-.jpg\"><img loading=\"lazy\" class=\"size-full wp-image-31034\" title=\"Ressurrei\u00e7\u00e3o \" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-.jpg\" alt=\"\" width=\"450\" height=\"518\" \/><\/a><figcaption id=\"caption-attachment-31034\" class=\"wp-caption-text\">Ressurrei\u00e7\u00e3o<\/figcaption><\/figure>\n<p style=\"padding-left: 90px;\"><span style=\"color: #800080;\"><strong><span style=\"font-family: verdana, geneva; font-size: medium;\">A Cerimonia se inicia com o fogo novo, a luz da igreja dizendo que a ressurrei\u00e7\u00e3o est\u00e1 pr\u00f3xima!<\/span><\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>Ben\u00e7\u00e3o do Lume Novo<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">As luzes da igreja est\u00e3o todas apagadas. Do lado de fora est\u00e1 um fogareiro preparado pelo sacrist\u00e3o antes do in\u00edcio das fun\u00e7\u00f5es, com a fa\u00edsca tirada de uma pedra.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> Ent\u00e3o o celebrante aben\u00e7oa o fogo e o turifer\u00e1rio recolhe algumas brasas bentas e as coloca no tur\u00edbulo. A pedra representa Cristo, &#8220;a pedra angular&#8221; que, sob os golpes da cruz, jorrou sobre n\u00f3s o Esp\u00edrito Santo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">O fogo novo, representativo da Ressurrei\u00e7\u00e3o de Nosso Senhor, luz Divina apagada por tr\u00eas dias, que h\u00e1 de aparecer ao p\u00e9 do t\u00famulo de Cristo, que se imagina exterior ao recinto da igreja, e resplandecer\u00e1 no Dia da Ressurrei\u00e7\u00e3o.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> Deve ser novo este fogo, porque Nosso Senhor, simbolizado por ele, acaba de sair do t\u00famulo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Essa cerim\u00f4nia era j\u00e1 conhecida nos primeiros s\u00e9culos da cristandade. Tem sua origem no costume romano de iluminar a noite com muitas l\u00e2mpadas. Essas l\u00e2mpadas passam a ser s\u00edmbolo do Senhor Ressuscitado, que surge de dentro da noite da morte.<\/span><\/p>\n<p>&nbsp;<\/p>\n<p><span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>A prociss\u00e3o com o C\u00edrio Pascal<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"><a href=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-1.jpg\"><img loading=\"lazy\" class=\"alignleft size-medium wp-image-31035\" title=\"Ressurrei\u00e7\u00e3o -\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-1-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" \/><\/a>Ap\u00f3s a cerim\u00f4nia de prepara\u00e7\u00e3o do C\u00edrio Pascal, \u00e9 ele solenemente introduzido no templo por um di\u00e1cono que, por tr\u00eas vezes, ao longo do cortejo pela nave central, canta elevando sucessivamente o tom: &#8220;Eis a luz de Cristo&#8221; (<em>Lumen Christi<\/em>). <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">O coro responde: &#8220;Gra\u00e7as a Deus&#8221; (<em>Deo Gratias<\/em>).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> Em cada parada v\u00e3o se acendendo aos poucos as velas: na primeira vez \u00e9 acesa a vela do celebrante; na segunda parada, feita no meio do corredor central, s\u00e3o acesas as velas dos cl\u00e9rigos; na terceira vez, por fim, se acendem as velas dos assistentes, que comunicam as chamas do C\u00edrio bento at\u00e9 toda a igreja estar iluminada.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">As velas s\u00e3o acesas no C\u00edrio Pascal, pois nossa luz vem de Cristo. O di\u00e1cono, que vem vindo, \u00e9, portanto, mensageiro e arauto da boa nova: anuncia ao povo a Ressurrei\u00e7\u00e3o de Cristo, como outrora o Anjo \u00e0s santas mulheres.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">As palavras\u00a0<em>Lumen Christi<\/em>\u00a0significam que Jesus Cristo \u00e9 a \u00fanica Luz do mundo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">A prociss\u00e3o, que se forma atr\u00e1s do C\u00edrio Pascal \u00e9 repleta de s\u00edmbolos. \u00c9 alus\u00e3o \u00e0s palavras de Nosso Senhor: &#8220;Eu Sou a Luz do mundo. Quem me segue n\u00e3o anda nas trevas, mas ter\u00e1 a Luz da Vida&#8221; (Jo 8,12; Jo 9,5; 12,46).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> O C\u00edrio, conduzido \u00e0 frente, recorda a coluna de fogo pela qual Deus precedia na escurid\u00e3o da noite ao povo de Israel ao sair da escravid\u00e3o do Egito e lhe mostrava o caminho (Ex 13, 21). <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">O crist\u00e3o \u00e9 aquele que, para iluminar, se deixa consumir na Luz maior, e que em sua luz acende outras, dando sua pr\u00f3pria vida, como ensinou e fez Nosso Senhor Jesus Cristo (Jo 15,13).<\/span><\/p>\n<p>&nbsp;<\/p>\n<div>\n<p><span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>O Prec\u00f4nio Pascal<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Ao t\u00e9rmino da prociss\u00e3o, na qual se introduz o C\u00edrio no Templo, \u00e9 ele colocado em local apropriado. Com a vela acesa na m\u00e3o, renovamos nossa f\u00e9, proclamando Jesus Cristo, Luz do mundo que ressurgiu das trevas para iluminar nosso caminho. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">E lembramos que por voca\u00e7\u00e3o todo crist\u00e3o \u00e9 chamado a ser tamb\u00e9m luz, como Ele mesmo nos diz: <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"><em>&#8220;V\u00f3s sois a luz do mundo. Que, portanto, brilhe vossa luz diante dos homens, para que as pessoas vejam vossas boas obras e glorifiquem vosso Pai, que est\u00e1 nos C\u00e9us!&#8221;<\/em> (Mt 5,14.16).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">O di\u00e1cono, ap\u00f3s incensar o C\u00edrio e o Livro, canta o Prec\u00f4nio Pascal, do latim\u00a0<em>Praeconium Pascale<\/em>, que significa Anuncia\u00e7\u00e3o da P\u00e1scoa (v\u00eddeo acima), em que se exaltam os benef\u00edcios da Reden\u00e7\u00e3o e que \u00e9 um belo poema, a partir da vela, sobre o trabalho das abelhas e o material para a sua confec\u00e7\u00e3o, o significado da luz ao longo da hist\u00f3ria de Israel e, de modo especial, sobre Jesus, a Luz do mundo. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">As magn\u00edficas palavras deste hino s\u00e3o atribu\u00eddas a Santo Ambr\u00f3sio e a Santo Agostinho. \u00c9 esse canto o antigo Lucern\u00e1rio da Vig\u00edlia Pascal. O nome Lucern\u00e1rio foi dado \u00e0s ora\u00e7\u00f5es que se diziam na reuni\u00e3o lit\u00fargica ao acenderem-se as luzes ao anoitecer (<a href=\"http:\/\/letras.mus.br\/catolicas\/exultet-praeconium-paschale-latim\/traducao.html\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000000;\">veja letra e tradu\u00e7\u00e3o aqui<\/span><\/a>).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Arder\u00e1 da\u00ed em diante o C\u00edrio Pascal, em todas as fun\u00e7\u00f5es, durante quarenta dias, recordando a perman\u00eancia na Terra de Cristo ressuscitado. Retirar-se-\u00e1 no dia da Ascens\u00e3o, isto \u00e9, no momento em que Jesus Cristo ressuscitado sobe ao C\u00e9u.<\/span><br \/>\n<span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>Leitura das Profecias<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Nos prim\u00f3rdios da Igreja, nesta hora, aproximavam-se os catec\u00famenos para receberem o Batismo. A fim de ocupar a aten\u00e7\u00e3o dos fi\u00e9is e para a maior instru\u00e7\u00e3o dos catec\u00famenos, liam-se na tribuna passagens da Sagrada Escritura apropriados ao ato. Eram as Doze Profecias, como resumo hist\u00f3rico da Religi\u00e3o: cria\u00e7\u00e3o, dil\u00favio, liberta\u00e7\u00e3o dos israelitas, or\u00e1culos messi\u00e2nicos.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Atualmente s\u00e3o feitas apenas nove leituras, sete do Antigo Testamento e duas do Novo. Para cada leitura, h\u00e1 uma ora\u00e7\u00e3o, com c\u00e2ntico ou salmo responsorial. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Ap\u00f3s a s\u00e9tima leitura, s\u00e3o acessas as velas do Altar a partir do C\u00edrio Pascal e o sacerdote entoa o canto do\u00a0<em>Gloria in Excelsis<\/em>, com acompanhamento de instrumentos musicais e de sinos, que ficaram calados durante todo o Tr\u00edduo sagrado. A Igreja, portanto, entra inteira na alegria pascal.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> Logo em seguida \u00e9 feita a primeira leitura do Novo Testamento (Rm 6,3-11), que \u00e9 sobre o Batismo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Ap\u00f3s o t\u00e9rmino das leituras, o sacerdote entoa o canto solene do &#8220;Aleluia&#8221;, quebrando o clima de tristeza e contri\u00e7\u00e3o que acompanhava todo o tempo da Quaresma. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Esse canto solene, repetido gradativamente tr\u00eas vezes em tom cada vez mais alto, representa a sa\u00edda de Cristo da sepultura e expressa o crescente j\u00fabilo pela Vit\u00f3ria do Salvador. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Por fim, proclama-se um trecho do Evangelho sobre a Ressurrei\u00e7\u00e3o de Jesus, levando-se em considera\u00e7\u00e3o o ciclo anual A, B e C.<\/span><br \/>\n<span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>Ben\u00e7\u00e3o da pia batismal<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"><a href=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-2.jpg\"><img loading=\"lazy\" class=\"alignleft  wp-image-31036\" title=\"Ressurrei\u00e7\u00e3o ---\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-2.jpg\" alt=\"\" width=\"350\" height=\"340\" \/><\/a>Terminada a leitura das Profecias, vai o Clero para a pia batismal. Na frente do cortejo, a Cruz e o C\u00edrio Pascal, s\u00edmbolos de Cristo que deve alumiar a nossa peregrina\u00e7\u00e3o terrena, como em outras eras a nuvem luminosa norteava o rumo dos israelitas no deserto.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">O celebrante aben\u00e7oa a \u00e1gua num magn\u00edfico pref\u00e1cio em que s\u00e3o lembradas as maravilhas que Deus quis operar por meio da \u00e1gua; depois, com a m\u00e3o divide em quatro partes a \u00e1gua j\u00e1 purificada, e derrama algumas gotas nos quatro pontos cardeais.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> Enfim, nessa pia batismal, mergulha por tr\u00eas vezes o C\u00edrio Pascal, simbolizando o poder regenerador que Jesus Ressuscitado d\u00e1 a essa \u00e1gua e, tamb\u00e9m, nossa participa\u00e7\u00e3o em seu Mist\u00e9rio Pascal, no qual morremos ao pecado e ressuscitamos para a vida da Gra\u00e7a. <\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">E ainda deita nela um pouco do \u00f3leo dos catec\u00famenos e do santo Crisma. Essa \u00e1gua ser\u00e1 usada nos batizados ao longo do ano e na aspers\u00e3o do povo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Quando n\u00e3o h\u00e1 Batismo-Confirma\u00e7\u00e3o, sempre se benze a \u00e1gua, que \u00e9 levada solenemente at\u00e9 a pia batismal.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Antigamente, ap\u00f3s os ritos preparat\u00f3rias, era administrado o Batismo solene aos catec\u00famenos (os que se iniciavam na f\u00e9 crist\u00e3) que, durante tr\u00eas anos, viviam um processo intenso de prepara\u00e7\u00e3o para ingressar na Igreja, com um rigor maior na Quaresma e na Semana Santa.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> Findos os ritos preparat\u00f3rios, os catec\u00famenos, jubilosos, eram levados ao lugar onde haveriam de receber o Batismo. A aspers\u00e3o dos fi\u00e9is que hoje em dia o celebrante faz, avan\u00e7ando atrav\u00e9s da igreja, com a \u00e1gua acabada de benzer,\u00a0recorda esta antiga cerim\u00f4nia\u00a0.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Depois da ben\u00e7\u00e3o da pia batismal, volta o pr\u00e9stito ao coro, cantando a Ladainha de Todos os Santos, recordando os que viveram com fidelidade a Gra\u00e7a Batismal. Chegados ao p\u00e9 do Altar, o celebrante e seus ministros prostram-se para meditar ainda na Morte e Sepultura de Nosso Senhor.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">O final do S\u00e1bado Santo, com seus tr\u00eas aspectos do mesmo e \u00fanico Mist\u00e9rio Pascal: Morte, Sepultamento e Ressurrei\u00e7\u00e3o de Jesus, est\u00e1 no \u00e1pice do Tr\u00edduo Pascal. Primeiro est\u00e1 a Morte na Sexta-feira; depois Jesus no t\u00famulo, no S\u00e1bado; e, em seguida, a Ressurrei\u00e7\u00e3o, no Domingo, iniciada, por\u00e9m, na noite de S\u00e1bado, por isso dito &#8220;S\u00e1bado de Aleluia&#8221;, na Vig\u00edlia Pascal.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">A Missa do S\u00e1bado Santo \u00e9 a primeira das duas cantadas na P\u00e1scoa. Esta Celebra\u00e7\u00e3o ostenta o car\u00e1ter de extremo j\u00fabilo e magnific\u00eancia, em forte contraste com a m\u00e1goa intensa da Sexta-feira Santa.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"> Vemos agora os Altares e os dignat\u00e1rios paramentados, em grande gala. Reboam as notas alegres do\u00a0<em>Gloria in Excelsis<\/em>, unidas ao eco dos sinos festivos! O Aleluia, n\u00e3o mais ouvido desde o in\u00edcio da Quaresma, ressurge ap\u00f3s a Ep\u00edstola. \u2013 Essa \u00e9, na realidade a Missa da madrugada da P\u00e1scoa. <\/span><\/p>\n<p><span style=\"color: #3366ff;\"><strong><span style=\"font-family: verdana, geneva;\">\u00c9 a celebra\u00e7\u00e3o, por assim dizer, da Aurora da Ressurrei\u00e7\u00e3o.<\/span><\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.aascj.org.br\/medalha-sao-bento\/?origem=1\"><img loading=\"lazy\" class=\"aligncenter  wp-image-31037\" title=\"Medalha de S. Bento\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/1861-top.jpg\" alt=\"\" width=\"480\" height=\"146\" \/><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>A Cerimonia se inicia com o fogo novo, a luz da igreja dizendo que a ressurrei\u00e7\u00e3o est\u00e1 pr\u00f3xima! &nbsp; Ben\u00e7\u00e3o do Lume Novo As luzes da igreja est\u00e3o todas apagadas. Do lado de fora est\u00e1 um fogareiro preparado pelo sacrist\u00e3o antes do in\u00edcio das fun\u00e7\u00f5es, com a fa\u00edsca tirada de uma pedra. Ent\u00e3o o celebrante [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[378,1326,1314,1327,102,1253],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Depois das trevas, Luz&quot; - Veja os significados da cerimonia de s\u00e1bado - Associa\u00e7\u00e3o Devotos de F\u00e1tima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Depois das trevas, Luz&quot; - Veja os significados da cerimonia de s\u00e1bado - Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"og:description\" content=\"A Cerimonia se inicia com o fogo novo, a luz da igreja dizendo que a ressurrei\u00e7\u00e3o est\u00e1 pr\u00f3xima! &nbsp; Ben\u00e7\u00e3o do Lume Novo As luzes da igreja est\u00e3o todas apagadas. Do lado de fora est\u00e1 um fogareiro preparado pelo sacrist\u00e3o antes do in\u00edcio das fun\u00e7\u00f5es, com a fa\u00edsca tirada de uma pedra. Ent\u00e3o o celebrante [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-04T16:00:32+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"victor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\\u00e7\\u00e3o-.jpg\",\"contentUrl\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\\u00e7\\u00e3o-.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/\",\"name\":\"\\\"Depois das trevas, Luz\\\" - Veja os significados da cerimonia de s\\u00e1bado - Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#primaryimage\"},\"datePublished\":\"2015-04-04T16:00:32+00:00\",\"dateModified\":\"2015-04-04T16:00:32+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Depois das trevas, Luz&#8221; &#8211; Veja os significados da cerimonia de s\\u00e1bado\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066\",\"name\":\"victor\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g\",\"caption\":\"victor\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/victor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Depois das trevas, Luz\" - Veja os significados da cerimonia de s\u00e1bado - Associa\u00e7\u00e3o Devotos de F\u00e1tima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/","og_locale":"pt_BR","og_type":"article","og_title":"\"Depois das trevas, Luz\" - Veja os significados da cerimonia de s\u00e1bado - Associa\u00e7\u00e3o Devotos de F\u00e1tima","og_description":"A Cerimonia se inicia com o fogo novo, a luz da igreja dizendo que a ressurrei\u00e7\u00e3o est\u00e1 pr\u00f3xima! &nbsp; Ben\u00e7\u00e3o do Lume Novo As luzes da igreja est\u00e3o todas apagadas. Do lado de fora est\u00e1 um fogareiro preparado pelo sacrist\u00e3o antes do in\u00edcio das fun\u00e7\u00f5es, com a fa\u00edsca tirada de uma pedra. Ent\u00e3o o celebrante [&hellip;]","og_url":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2015-04-04T16:00:32+00:00","og_image":[{"url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"victor","Est. tempo de leitura":"8 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-.jpg","contentUrl":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/04\/Ressurrei\u00e7\u00e3o-.jpg"},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#webpage","url":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/","name":"\"Depois das trevas, Luz\" - Veja os significados da cerimonia de s\u00e1bado - Associa\u00e7\u00e3o Devotos de F\u00e1tima","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#primaryimage"},"datePublished":"2015-04-04T16:00:32+00:00","dateModified":"2015-04-04T16:00:32+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066"},"breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/depois-das-trevas-luz-veja-os-significados-da-cerimonia-de-sabado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"&#8220;Depois das trevas, Luz&#8221; &#8211; Veja os significados da cerimonia de s\u00e1bado"}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066","name":"victor","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g","caption":"victor"},"url":"https:\/\/www.adf.org.br\/home\/author\/victor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/31032"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=31032"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/31032\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=31032"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=31032"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=31032"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}