{"id":30235,"date":"2015-03-23T21:00:03","date_gmt":"2015-03-24T00:00:03","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=30235"},"modified":"2015-03-23T21:00:03","modified_gmt":"2015-03-24T00:00:03","slug":"as-dores-de-nossa-senhora-profecia-de-simeao","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/","title":{"rendered":"As Dores de Nossa Senhora &#8211; Profecia de Sime\u00e3o"},"content":{"rendered":"<p>&nbsp;<\/p>\n<figure id=\"attachment_30251\" aria-describedby=\"caption-attachment-30251\" style=\"width: 306px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.adf.org.br\/home\/2015\/03\/as-dores-de-nossa-senhora-profecia-de-simeao\/1-primeira\/\" rel=\"attachment wp-att-30251\"><img loading=\"lazy\" class=\"size-full wp-image-30251\" title=\"primeira dor\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1-primeira.jpg\" alt=\"\" width=\"306\" height=\"404\" \/><\/a><figcaption id=\"caption-attachment-30251\" class=\"wp-caption-text\">Apresenta\u00e7\u00e3o do Menino Jesus<\/figcaption><\/figure>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>&#8220;Oh Santa M\u00e3e, fixai as chagas do Crucificado<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>fortemente em meu cora\u00e7\u00e3o;<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>de Vosso Filho ferido que por mim quis sofrer,<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>partilhai comigo as dores.&#8221;<\/em><\/span><\/p>\n<p style=\"padding-left: 60px;\"><span style=\"font-size: medium;\"><strong>A Primeira ferida<\/strong><\/span><\/p>\n<p>\u00a0A ferida inicial foi a profecia de Sime\u00e3o. O Divino Menino, com a idade de quarenta dias, foi levado ao Templo; mal Sime\u00e3o teve em seus bra\u00e7os a Luz do Mundo, logo de seus l\u00e1bios saiu o canto do cisne: est\u00e1 pronto a morrer, porque viu o Salvador. Depois de ter anunciado que esse menino ser\u00e1 objeto de contradi\u00e7\u00e3o, disse a Maria:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #3366ff;\">&#8220;<\/span><em style=\"color: #3366ff;\"><strong>A Tua alma ser\u00e1 trespassada por uma espada de dor<\/strong><\/em><span style=\"color: #3366ff;\">.&#8221;<\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Notai que Sime\u00e3o n\u00e3o disse que uma espada lhe trespassaria o corpo. A lan\u00e7a do centuri\u00e3o poderia trespassar o Corpo de Cristo; o Seu Corpo poderia ter sido ferido ao ponto de <strong>&#8220;<em>os seus ossos se poderem contar<\/em>&#8220;<\/strong>, mas o Corpo de Maria ser\u00e1 poupado.<\/p>\n<p>Assim como, na Anuncia\u00e7\u00e3o, quando Ela concebeu, o \u00eaxtase &#8211; ao contr\u00e1rio do amor humano &#8211; foi, primeiro, na sua alma, e, depois, no seu corpo,\u00a0assim, na sua compaix\u00e3o, as dores do mart\u00edrio penetram primeiro a sua alma, para depois terem resson\u00e2ncia no seu corpo, como eco de todos os golpes com que a carne de Seu Filho foi flagelada, com que as Suas m\u00e3os e os Seus p\u00e9s foram trespassados.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #800080;\"><strong>A Espada s\u00f3 tem quarenta dias e todavia j\u00e1 sabe como ferir. Desde a\u00ed, quando Maria tocar nas m\u00e3os dum menino, nelas ver\u00e1 a sombra de um prego. Se o seu cora\u00e7\u00e3o houvesse de formar um s\u00f3 com o de Jesus, ent\u00e3o, como Ele, devia ela ver todos os pores-de-sol tintos do sangue da Paix\u00e3o. As Suas pequeninas pulsa\u00e7\u00f5es seriam, para o seu cora\u00e7\u00e3o, a tr\u00e1gica advert\u00eancia dos terr\u00edveis martelos<\/strong>.<\/span><\/p>\n<p>&nbsp;<\/p>\n<figure id=\"attachment_30266\" aria-describedby=\"caption-attachment-30266\" style=\"width: 300px\" class=\"wp-caption alignleft\"><a href=\"http:\/\/www.adf.org.br\/home\/2015\/03\/as-dores-de-nossa-senhora-profecia-de-simeao\/nossa-senhora-das-dores-7\/\" rel=\"attachment wp-att-30266\"><img loading=\"lazy\" class=\"size-medium wp-image-30266\" title=\"Nossa Senhora das Dores\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/Nossa-Senhora-das-Dores-300x236.jpg\" alt=\"\" width=\"300\" height=\"236\" \/><\/a><figcaption id=\"caption-attachment-30266\" class=\"wp-caption-text\">Nossa Senhora das Dores<\/figcaption><\/figure>\n<p>A sua dor n\u00e3o ser\u00e1 o que ela sofre, mas saber o que Ele sofrer\u00e1&#8230;O gume da espada destinado ao Salvador significava, para sua M\u00e3e, pela boca de Sime\u00e3o, que Ele devia ser v\u00edtima para o pecado. A parte que a ela dizia respeito consistia em saber que, at\u00e9 \u00e0 hora do supremo sacrif\u00edcio, ela era respons\u00e1vel pela vida de Jesus.<\/p>\n<p>Com uma s\u00f3 palavra, Sime\u00e3o previu a Crucifix\u00e3o\u00a0e a sua dor.<\/p>\n<p><strong>Mal essa nova barca foi lan\u00e7ada \u00e0s \u00e1guas da vida, logo um anci\u00e3o lhe anunciou o naufr\u00e1gio<\/strong>.\u00a0A M\u00e3e teve quarenta dias para beijar o Seu Filho com alegria. S\u00f3; mais nada. A sombra da contradi\u00e7\u00e3o alastra para sempre sobre o seu futuro. Maria n\u00e3o beber\u00e1, decerto, o c\u00e1lice do pecado, nem a borra amarga que Seu Filho beber\u00e1 no Jardim das Oliveiras; todavia, Ele lhe aproximar\u00e1 dos l\u00e1bios o c\u00e1lice.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #3366ff;\"><strong>A hostilidade do Mundo \u00e9 o pr\u00eamio que cabe a todos aqueles que pertencem a Jesus. Quantos convertidos n\u00e3o t\u00eam sentido o fanatismo ou o desprezo daqueles que lhes censuram o terem deixado a mediocridade do Mundo pelas alturas do sobrenatural!<\/strong><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>Nosso Senhor, falando dessa oposi\u00e7\u00e3o, disse:<\/p>\n<p>&nbsp;<\/p>\n<p style=\"padding-left: 30px;\"><span style=\"color: #800080;\"><em>&#8220;Vim para trazer a espada com que separe o pai do filho, a m\u00e3e de sua filha.&#8221;<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Se o crente sente a contradi\u00e7\u00e3o, quanto mais a n\u00e3o sentir\u00e1 Maria, M\u00e3e d&#8217;Aquele que iria conduzir a Cruz, s\u00edmbolo da contradi\u00e7\u00e3o. Mas uma vez que Cristo trazia a espada ao Mundo, devia ser sua M\u00e3e a primeira a experiment\u00e1-la, n\u00e3o como v\u00edtima involunt\u00e1ria, mas pronunciando livremente o seu FIAT, para a Ele se unir no ato da Reden\u00e7\u00e3o.<\/strong><\/p>\n<p>Se v\u00f3s f\u00f4sseis o \u00fanico de olhos abertos num mundo de cegos, n\u00e3o querer\u00edeis ser o seu amparo?<\/p>\n<p>Se a bondade se comove perante as feridas, n\u00e3o tentar\u00e1 a virtude, perante o pecado, cooperar na obra d&#8217;Aquele que limpa os pecados?<\/p>\n<p><strong>Se Maria, sem pecado, aceita com alegria a espada que lhe vem da Divindade sem mancha, qual de n\u00f3s, pecadores, se lamentaria, quando o pr\u00f3prio Jesus nos permite sofrer pela remiss\u00e3o das nossas faltas?<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>&#8220;\u00d3 Maria, trespassada de dores;<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>Salvai-nos! Tocai e salvai<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>a alma daquele que amanh\u00e3 comparecer\u00e1 perante o Todo-Poderoso;<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>Uma vez que todo o homem nasceu de uma mulher<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>por cada um que disso precise,<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>amigo leal ou inimigo corajoso,<\/em><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"color: #800080;\"><em>Intercede, Tu, \u00f3 Senhora!&#8221;<\/em><\/span><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>(O Primeiro Amor do Mundo &#8211; Arcebispo Fulton J. Sheen)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.adf.org.br\/livro-padre-pio\/inicio-1\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-30271\" title=\"Padre Pio\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/botao_pe-pio1.jpg\" alt=\"\" width=\"384\" height=\"163\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; &#8220;Oh Santa M\u00e3e, fixai as chagas do Crucificado fortemente em meu cora\u00e7\u00e3o; de Vosso Filho ferido que por mim quis sofrer, partilhai comigo as dores.&#8221; A Primeira ferida \u00a0A ferida inicial foi a profecia de Sime\u00e3o. O Divino Menino, com a idade de quarenta dias, foi levado ao Templo; mal Sime\u00e3o teve em seus [&hellip;]<\/p>\n","protected":false},"author":22,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[740,1197,432,1198],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>As Dores de Nossa Senhora - Profecia de Sime\u00e3o - Associa\u00e7\u00e3o Devotos de F\u00e1tima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As Dores de Nossa Senhora - Profecia de Sime\u00e3o - Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"og:description\" content=\"&nbsp; &#8220;Oh Santa M\u00e3e, fixai as chagas do Crucificado fortemente em meu cora\u00e7\u00e3o; de Vosso Filho ferido que por mim quis sofrer, partilhai comigo as dores.&#8221; A Primeira ferida \u00a0A ferida inicial foi a profecia de Sime\u00e3o. O Divino Menino, com a idade de quarenta dias, foi levado ao Templo; mal Sime\u00e3o teve em seus [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-24T00:00:03+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1-primeira.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"victor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1-primeira.jpg\",\"contentUrl\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1-primeira.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/\",\"name\":\"As Dores de Nossa Senhora - Profecia de Sime\\u00e3o - Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#primaryimage\"},\"datePublished\":\"2015-03-24T00:00:03+00:00\",\"dateModified\":\"2015-03-24T00:00:03+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As Dores de Nossa Senhora &#8211; Profecia de Sime\\u00e3o\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066\",\"name\":\"victor\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g\",\"caption\":\"victor\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/victor\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As Dores de Nossa Senhora - Profecia de Sime\u00e3o - Associa\u00e7\u00e3o Devotos de F\u00e1tima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/","og_locale":"pt_BR","og_type":"article","og_title":"As Dores de Nossa Senhora - Profecia de Sime\u00e3o - Associa\u00e7\u00e3o Devotos de F\u00e1tima","og_description":"&nbsp; &#8220;Oh Santa M\u00e3e, fixai as chagas do Crucificado fortemente em meu cora\u00e7\u00e3o; de Vosso Filho ferido que por mim quis sofrer, partilhai comigo as dores.&#8221; A Primeira ferida \u00a0A ferida inicial foi a profecia de Sime\u00e3o. O Divino Menino, com a idade de quarenta dias, foi levado ao Templo; mal Sime\u00e3o teve em seus [&hellip;]","og_url":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2015-03-24T00:00:03+00:00","og_image":[{"url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1-primeira.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"victor","Est. tempo de leitura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1-primeira.jpg","contentUrl":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1-primeira.jpg"},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#webpage","url":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/","name":"As Dores de Nossa Senhora - Profecia de Sime\u00e3o - Associa\u00e7\u00e3o Devotos de F\u00e1tima","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#primaryimage"},"datePublished":"2015-03-24T00:00:03+00:00","dateModified":"2015-03-24T00:00:03+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066"},"breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/as-dores-de-nossa-senhora-profecia-de-simeao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"As Dores de Nossa Senhora &#8211; Profecia de Sime\u00e3o"}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/84ab1f4a9c9c8771882d949dd0995066","name":"victor","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/22216f0aeebc0f960e28a73506b4d08c?s=96&d=mm&r=g","caption":"victor"},"url":"https:\/\/www.adf.org.br\/home\/author\/victor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/30235"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/22"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=30235"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/30235\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=30235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=30235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=30235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}