{"id":30227,"date":"2015-03-24T11:00:55","date_gmt":"2015-03-24T14:00:55","guid":{"rendered":"http:\/\/www.adf.org.br\/home\/?p=30227"},"modified":"2015-03-24T11:00:55","modified_gmt":"2015-03-24T14:00:55","slug":"inferno-os-tempos-mudaram","status":"publish","type":"post","link":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/","title":{"rendered":"Inferno: os tempos mudaram?"},"content":{"rendered":"<figure id=\"attachment_30228\" aria-describedby=\"caption-attachment-30228\" style=\"width: 356px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.adf.org.br\/home\/2015\/03\/inferno-os-tempos-mudaram\/aphoto-r-m-n-r-g-ojada\/\" rel=\"attachment wp-att-30228\"><img loading=\"lazy\" class=\" wp-image-30228  \" title=\"\u201cO Inferno\u201d. Iluminura do livro \u201cLes Tr\u00e8s Riches Heures du duc de Berry\u201d (Atualmente conservado no museu Cond\u00e9, em Chantilly).\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/\u201cO-Inferno\u201d.-Iluminura-do-livro-\u201cLes-Tr\u00e8s-Riches-Heures-du-duc-de-Berry\u201d-Atualmente-conservado-no-museu-Cond\u00e9-em-Chantilly.-741x1024.jpg\" alt=\"\" width=\"356\" height=\"491\" \/><\/a><figcaption id=\"caption-attachment-30228\" class=\"wp-caption-text\">\u201cO Inferno\u201d. Iluminura do livro \u201cLes Tr\u00e8s Riches Heures du duc de Berry\u201d (Atualmente conservado no museu Cond\u00e9, em Chantilly).<\/figcaption><\/figure>\n<p style=\"text-align: right;\"><span style=\"font-family: verdana, geneva; color: #000000;\"><em>Rev. Pe. David Francisquini<\/em><\/span><\/p>\n<p style=\"padding-left: 90px;\"><span style=\"font-family: verdana, geneva; font-size: medium; color: #800080;\"><strong>Imaginemos um te\u00f3logo em cujo esp\u00edrito germinasse uma ideia nova&#8230;<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">&#8230;sobre uma doutrina j\u00e1 consagrada e sempre ensinada na Igreja Cat\u00f3lica, qual seja a da\u00a0<strong>exist\u00eancia do inferno<\/strong>\u00a0e de sua eternidade.\u00a0Era de se supor que ele bem poderia colocar em risco seu futuro e cair no ostracismo.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Em n\u00e3o long\u00ednquo passado o ex-frei Leonardo Boff foi condenado pela Sagrada Congrega\u00e7\u00e3o para a Doutrina da F\u00e9 e reduzido ao sil\u00eancio por defender erros teol\u00f3gicos.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Ele voltou a ensinar o erro ao afirmar, a respeito de um poeta pernambucano prestes a morrer, que Deus n\u00e3o condena ningu\u00e9m para sempre.<\/span><\/p>\n<p style=\"padding-left: 60px;\"><span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>Ora, a f\u00e9 nos assegura que o fogo do inferno e os tormentos dos condenados s\u00e3o eternos. N\u00e3o se trata de opini\u00f5es controvertidas entre os te\u00f3logos e estudiosos.<\/strong><\/span><\/p>\n<p style=\"padding-left: 60px;\"><strong><span style=\"font-family: verdana, geneva; color: #800080;\">A\u00a0eternidade do inferno \u00e9 uma verdade de f\u00e9\u00a0que nenhuma autoridade pode mudar \u2014\u00a0nem sequer o Papa\u00a0\u2014, pois est\u00e1 expressa nas pr\u00f3prias Sagradas Escrituras, tanto no Antigo quanto no Novo Testamento.<\/span><\/strong><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">As Escrituras op\u00f5em-se \u00e0 ideia de que o inferno n\u00e3o seja eterno ao afirmar:\u00a0<em>\u201cApartai-vos de mim, malditos, para o fogo eterno\u201d<\/em>\u00a0(Mt 25, 41).<\/span><\/p>\n<p style=\"padding-left: 60px;\"><span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>De onde se segue que, se o fogo \u00e9 eterno, tamb\u00e9m o \u00e9 o supl\u00edcio do condenado. N\u00e3o haveria raz\u00e3o para Deus ter criado um fogo eterno se n\u00e3o fosse para castigar eternamente os condenados.<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Em outro lugar nas Escrituras pode-se ler:\u00a0<em>\u201cIr\u00e3o estes para o fogo eterno\u201d<\/em>\u00a0(idem 46).\u00a0<em>\u201cIr para a geena, para o fogo inextingu\u00edvel, onde o seu verme n\u00e3o morre e o fogo n\u00e3o se apaga\u201d<\/em>\u00a0(Mc 9, 43<\/span><br \/>\n<span style=\"font-family: verdana, geneva; color: #000000;\">a 44).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">No Apocalipse 14, 11 est\u00e1 escrito:\u00a0<em>\u201cA fuma\u00e7a dos seus tormentos subir\u00e1 pelos s\u00e9culos dos s\u00e9culos. N\u00e3o ter\u00e3o descanso algum, nem de dia nem de noite, esses que adoram a besta e a sua imagem, e todo aquele que acaso tenha recebido o sinal do seu nome\u201d.<\/em><\/span><\/p>\n<p style=\"padding-left: 60px;\"><span style=\"font-family: verdana, geneva; color: #800080;\"><strong>Uma pena que n\u00e3o fosse eterna \u2014 e durasse pouco \u2014 faria com que o inferno deixasse de ser inferno e Deus deixasse de ser Deus.<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; font-size: medium; color: #000000;\"><strong>O Castigo e o Pr\u00eamio s\u00e3o eternos<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Ao meditar sobre a eternidade do inferno, Santo Afonso Maria de Lig\u00f3rio nos sugere multiplicar todos os milh\u00f5es de anos em infinitas vezes. O resultado dessa multiplica\u00e7\u00e3o mostraria que o inferno estaria apenas come\u00e7ando\u2026<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Uma coisa \u00e9 a bondade de Deus, que persegue o pecador para convert\u00ea-lo, afast\u00e1-lo do mau caminho, concedendo-lhe gra\u00e7as, dons, e at\u00e9 mesmo castigos.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Outra coisa \u00e9 a bondade e a miseric\u00f3rdia da Igreja, sempre de cora\u00e7\u00e3o aberto e m\u00e3os estendidas para<strong>\u00a0receber e perdoar o pecador convertido.<\/strong><\/span><\/p>\n<p style=\"padding-left: 60px;\"><span style=\"font-family: verdana, geneva; color: #3366ff;\"><strong>N\u00e3o podemos confundir esse pecador com aquele que n\u00e3o abandona o seu mau procedimento e morre empedernido. Se assim viveu e morreu foi por sua pr\u00f3pria culpa.<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Escolheu livre e espontaneamente o lugar que se chama inferno. Deus d\u00e1 o pr\u00eamio aos bons e o castigo aos maus.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Como Deus \u00e9 eterno,\u00a0<strong>tamb\u00e9m eternos s\u00e3o o pr\u00eamio e o castigo<\/strong>. Deus deixaria de ser Deus se fosse apenas misericordioso e n\u00e3o desse o pr\u00eamio e o castigo de acordo com as obras. Deus \u00e9 misericordioso porque justo. Esta eternidade \u00e9 de f\u00e9, porque revelada por Deus, e n\u00e3o uma simples opini\u00e3o.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"><em>\u00a0\u201cApartai-vos de Mim malditos para o fogo eterno. Ir\u00e3o estes ao supl\u00edcio eterno. Pagar\u00e3o a pena da eterna perdi\u00e7\u00e3o. Todos ser\u00e3o assolados pelo fogo\u201d<\/em>\u00a0(Mt 25, 41. 46; 1Ts1,8; Mc 9,48).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Assim como o sal conserva o alimento, o fogo do inferno atormenta os condenados, mas ao mesmo tempo tem a propriedade do sal ao conservar-lhes a vida.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"><em>\u201cAli o fogo consome de tal modo<\/em>\u00a0\u2014 disse S\u00e3o Bernardo \u2014\u00a0<em>que conserva sempre\u201d<\/em>. Santo Afonso ensina:<em>\u201cO po\u00e7o n\u00e3o fecha a sua boca, porque se fechar a abertura em cima, se abrir\u00e1 em baixo para devorar os r\u00e9probos\u201d.\u00a0<\/em><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"><em><\/em>Continua ele:<em>\u00a0\u201cEnquanto vivo, o pecador pode ter alguma esperan\u00e7a, m<\/em><em>as, se a morte o surpreender em pecado, perder\u00e1 toda esperan\u00e7a\u201d<\/em>\u00a0(Pr 11,7).<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Se os condenados pudessem ao menos embalar-se em alguma\u00a0<strong>enganosa ilus\u00e3o<\/strong>\u00a0que aliviasse o seu desespero horr\u00edvel\u2026 Afinal, um infeliz delinquente condenado \u00e0 pris\u00e3o perp\u00e9tua tamb\u00e9m procura al\u00edvio em seu pesar, na esperan\u00e7a remota de evadir-se e obter assim a liberdade.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Mas o condenado n\u00e3o pode sequer ter a ilus\u00e3o de que um dia poder\u00e1 sair de sua pris\u00e3o! N\u00e3o, no inferno\u00a0<strong>n\u00e3o h\u00e1 esperan\u00e7a<\/strong>. O desgra\u00e7ado r\u00e9probo ter\u00e1 sempre diante de si a senten\u00e7a que o obriga a gemer perpetuamente nesse c\u00e1rcere de sofrimentos.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\"><em>\u201cUns para a vida eterna, e outros para o opr\u00f3brio que ter\u00e3o sempre diante dos olhos\u201d<\/em>\u00a0(Dn 12,2). Para Santo Afonso, o r\u00e9probo n\u00e3o sofre somente a pena de cada instante, mas sofre a cada instante a pena da eternidade.<\/span><\/p>\n<p><span style=\"font-family: verdana, geneva; color: #000000;\">Eis o que est\u00e1 escrito no Eclesiastes:\u00a0<em>\u201cQuando as nuvens estiverem carregadas, derramar\u00e3o chuvas sobre a terra. Se a \u00e1rvore cair para a parte do meio dia, ou para a do norte, em qualquer lugar onde cair, ficar\u00e1\u201d<\/em>\u00a0(Ecl. 11, 3).<\/span><\/p>\n<div>\n<p style=\"padding-left: 60px;\"><span style=\"font-family: verdana, geneva; color: #800080;\"><strong>Tal \u00e9 a sorte do justo e do pecador: ficar\u00e1 para sempre, no C\u00e9u ou no inferno.<\/strong><\/span><\/p>\n<p style=\"text-align: center;\"><span style=\"font-family: verdana, geneva;\"><strong>* \u00a0 * \u00a0 *<\/strong><\/span><\/p>\n<p><span style=\"font-family: verdana, geneva;\"><em>Fonte:<a href=\"http:\/\/www.abim.inf.br\/inferno-os-tempos-mudaram\/#.VRAtF9LF-NZ\" target=\"_blank\" rel=\"noopener noreferrer\">\u00a0http:\/\/www.abim.inf.br\/<\/a><\/em><\/span><\/p>\n<p><a href=\"http:\/\/www.santorosario.com.br\/?origem=1\"><img loading=\"lazy\" class=\"aligncenter size-full wp-image-30229\" title=\"Clique aqui e veja como receber em casa este lindo Ter\u00e7o!\" src=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/1984_topo6.jpg\" alt=\"\" width=\"600\" height=\"335\" \/><\/a><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Rev. Pe. David Francisquini Imaginemos um te\u00f3logo em cujo esp\u00edrito germinasse uma ideia nova&#8230; &#8230;sobre uma doutrina j\u00e1 consagrada e sempre ensinada na Igreja Cat\u00f3lica, qual seja a da\u00a0exist\u00eancia do inferno\u00a0e de sua eternidade.\u00a0Era de se supor que ele bem poderia colocar em risco seu futuro e cair no ostracismo. Em n\u00e3o long\u00ednquo passado o [&hellip;]<\/p>\n","protected":false},"author":12,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[20],"tags":[282,1194,1195,1196],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Inferno: os tempos mudaram? - Associa\u00e7\u00e3o Devotos de F\u00e1tima<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Inferno: os tempos mudaram? - Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"og:description\" content=\"Rev. Pe. David Francisquini Imaginemos um te\u00f3logo em cujo esp\u00edrito germinasse uma ideia nova&#8230; &#8230;sobre uma doutrina j\u00e1 consagrada e sempre ensinada na Igreja Cat\u00f3lica, qual seja a da\u00a0exist\u00eancia do inferno\u00a0e de sua eternidade.\u00a0Era de se supor que ele bem poderia colocar em risco seu futuro e cair no ostracismo. Em n\u00e3o long\u00ednquo passado o [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/\" \/>\n<meta property=\"og:site_name\" content=\"Associa\u00e7\u00e3o Devotos de F\u00e1tima\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-24T14:00:55+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/\u201cO-Inferno\u201d.-Iluminura-do-livro-\u201cLes-Tr\u00e8s-Riches-Heures-du-duc-de-Berry\u201d-Atualmente-conservado-no-museu-Cond\u00e9-em-Chantilly.-741x1024.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"luiz.fernando\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. tempo de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\",\"url\":\"https:\/\/www.adf.org.br\/home\/\",\"name\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"description\":\"Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.adf.org.br\/home\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#primaryimage\",\"inLanguage\":\"pt-BR\",\"url\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/\\u201cO-Inferno\\u201d.-Iluminura-do-livro-\\u201cLes-Tr\\u00e8s-Riches-Heures-du-duc-de-Berry\\u201d-Atualmente-conservado-no-museu-Cond\\u00e9-em-Chantilly.-741x1024.jpg\",\"contentUrl\":\"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/\\u201cO-Inferno\\u201d.-Iluminura-do-livro-\\u201cLes-Tr\\u00e8s-Riches-Heures-du-duc-de-Berry\\u201d-Atualmente-conservado-no-museu-Cond\\u00e9-em-Chantilly.-741x1024.jpg\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#webpage\",\"url\":\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/\",\"name\":\"Inferno: os tempos mudaram? - Associa\\u00e7\\u00e3o Devotos de F\\u00e1tima\",\"isPartOf\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#primaryimage\"},\"datePublished\":\"2015-03-24T14:00:55+00:00\",\"dateModified\":\"2015-03-24T14:00:55+00:00\",\"author\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/4eb0499131c1962e974297eff367a715\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.adf.org.br\/home\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Inferno: os tempos mudaram?\"}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/4eb0499131c1962e974297eff367a715\",\"name\":\"luiz.fernando\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.adf.org.br\/home\/#personlogo\",\"inLanguage\":\"pt-BR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/4e9dcdc2a00e06e1d9189a84f6908f28?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/4e9dcdc2a00e06e1d9189a84f6908f28?s=96&d=mm&r=g\",\"caption\":\"luiz.fernando\"},\"url\":\"https:\/\/www.adf.org.br\/home\/author\/luiz-fernando\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Inferno: os tempos mudaram? - Associa\u00e7\u00e3o Devotos de F\u00e1tima","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/","og_locale":"pt_BR","og_type":"article","og_title":"Inferno: os tempos mudaram? - Associa\u00e7\u00e3o Devotos de F\u00e1tima","og_description":"Rev. Pe. David Francisquini Imaginemos um te\u00f3logo em cujo esp\u00edrito germinasse uma ideia nova&#8230; &#8230;sobre uma doutrina j\u00e1 consagrada e sempre ensinada na Igreja Cat\u00f3lica, qual seja a da\u00a0exist\u00eancia do inferno\u00a0e de sua eternidade.\u00a0Era de se supor que ele bem poderia colocar em risco seu futuro e cair no ostracismo. Em n\u00e3o long\u00ednquo passado o [&hellip;]","og_url":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/","og_site_name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","article_published_time":"2015-03-24T14:00:55+00:00","og_image":[{"url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/\u201cO-Inferno\u201d.-Iluminura-do-livro-\u201cLes-Tr\u00e8s-Riches-Heures-du-duc-de-Berry\u201d-Atualmente-conservado-no-museu-Cond\u00e9-em-Chantilly.-741x1024.jpg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"luiz.fernando","Est. tempo de leitura":"5 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.adf.org.br\/home\/#website","url":"https:\/\/www.adf.org.br\/home\/","name":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","description":"Associa\u00e7\u00e3o Devotos de F\u00e1tima","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.adf.org.br\/home\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"pt-BR"},{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#primaryimage","inLanguage":"pt-BR","url":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/\u201cO-Inferno\u201d.-Iluminura-do-livro-\u201cLes-Tr\u00e8s-Riches-Heures-du-duc-de-Berry\u201d-Atualmente-conservado-no-museu-Cond\u00e9-em-Chantilly.-741x1024.jpg","contentUrl":"http:\/\/www.adf.org.br\/home\/wp-content\/uploads\/2015\/03\/\u201cO-Inferno\u201d.-Iluminura-do-livro-\u201cLes-Tr\u00e8s-Riches-Heures-du-duc-de-Berry\u201d-Atualmente-conservado-no-museu-Cond\u00e9-em-Chantilly.-741x1024.jpg"},{"@type":"WebPage","@id":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#webpage","url":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/","name":"Inferno: os tempos mudaram? - Associa\u00e7\u00e3o Devotos de F\u00e1tima","isPartOf":{"@id":"https:\/\/www.adf.org.br\/home\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#primaryimage"},"datePublished":"2015-03-24T14:00:55+00:00","dateModified":"2015-03-24T14:00:55+00:00","author":{"@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/4eb0499131c1962e974297eff367a715"},"breadcrumb":{"@id":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.adf.org.br\/home\/inferno-os-tempos-mudaram\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.adf.org.br\/home\/"},{"@type":"ListItem","position":2,"name":"Inferno: os tempos mudaram?"}]},{"@type":"Person","@id":"https:\/\/www.adf.org.br\/home\/#\/schema\/person\/4eb0499131c1962e974297eff367a715","name":"luiz.fernando","image":{"@type":"ImageObject","@id":"https:\/\/www.adf.org.br\/home\/#personlogo","inLanguage":"pt-BR","url":"https:\/\/secure.gravatar.com\/avatar\/4e9dcdc2a00e06e1d9189a84f6908f28?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/4e9dcdc2a00e06e1d9189a84f6908f28?s=96&d=mm&r=g","caption":"luiz.fernando"},"url":"https:\/\/www.adf.org.br\/home\/author\/luiz-fernando\/"}]}},"_links":{"self":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/30227"}],"collection":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/comments?post=30227"}],"version-history":[{"count":0,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/posts\/30227\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/media?parent=30227"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/categories?post=30227"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.adf.org.br\/home\/wp-json\/wp\/v2\/tags?post=30227"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}